{"id":10267,"date":"2021-10-12T16:46:00","date_gmt":"2021-10-12T14:46:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=10267"},"modified":"2022-08-02T17:12:22","modified_gmt":"2022-08-02T15:12:22","slug":"conte-de-lemploye-aux-abattoirs-nuits-282-a-285","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/10\/12\/conte-de-lemploye-aux-abattoirs-nuits-282-a-285\/","title":{"rendered":"Conte de l&#8217;employ\u00e9 aux abattoirs &#8211; Nuits 282 \u00e0 285"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&#8217;employ\u00e9 des abattoirs se fait enlever par les eunuques d&#8217;un harem, emmener dans un palais, laver, habiller et pr\u00e9senter \u00e0 une jeune femme qui le garde pour la nuit. Ceci huit jour de suite. Elle lui avoue \u00e0 la fin qu&#8217;elle fait \u00e7a pour se venger de son mari qui couche avec la servante et que donc elle a cherch\u00e9 l&#8217;homme le plus sale et le plus d\u00e9goutant qu&#8217;elle pouvait trouver. <\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>&#8220;Ah ! Laisse-moi baiser dix fois cette main gauche,<br>combien plus g\u00e9n\u00e9reuse que l&#8217;autre, tu vois bien :<br>Fid\u00e8le, la gauche le fut bien davantage<br>quand il fallut laver l&#8217;impur de ses ordures.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;employ\u00e9 des abattoirs se fait enlever par les eunuques d&#8217;un harem, emmener dans un palais, laver, habiller et pr\u00e9senter \u00e0 une jeune femme qui le garde pour la nuit. Ceci huit jour de suite. Elle lui avoue \u00e0 la fin qu&#8217;elle fait \u00e7a pour se venger de son mari qui couche avec la servante et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10268,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[85,104,65],"class_list":["post-10267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-mille-et-une-nuits","tag-infidelity","tag-revenge","tag-sadness"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2022\/08\/olivia-smith-QaxYzs6ysFQ-unsplash-scaled.jpg?fit=1707%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/10267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=10267"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/10267\/revisions"}],"predecessor-version":[{"id":10295,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/10267\/revisions\/10295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/10268"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=10267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=10267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=10267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}