{"id":10276,"date":"2021-10-24T17:49:00","date_gmt":"2021-10-24T15:49:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=10276"},"modified":"2022-08-02T17:57:33","modified_gmt":"2022-08-02T15:57:33","slug":"conte-de-harun-ar-rashid-de-la-jeune-escalve-et-de-limam-abu-yusuf-nuits-296-a-297","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/10\/24\/conte-de-harun-ar-rashid-de-la-jeune-escalve-et-de-limam-abu-yusuf-nuits-296-a-297\/","title":{"rendered":"Conte de H\u00e2r\u00fbn ar-Rash\u00eed, de la jeune escalve et de l&#8217;imam Ab\u00fb Y\u00fbsuf &#8211; Nuits 296 \u00e0 297"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">H\u00e2r\u00fbn ar-Rashid veut une esclave de son calife. Ils d\u00e9cident de la partager. Puis H\u00e2r\u00fbn veut la poss\u00e9der tout de suite et ceci est arrang\u00e9 en jouant avec les lois et les r\u00e8glements et la mariant \u00e0 un esclave non affranchi. Mais cet esclave refusant ensuite de r\u00e9pudier la jeune esclave convoit\u00e9e, un autre tour de passe-passe qui consiste \u00e0 donner l&#8217;esclave \u00e0 la jeune fille permettra \u00e0 H\u00e2r\u00fbn de faire ce qu&#8217;il veut avec celle-ci.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;On raconte encore, Sire, \u00f4 roi bienheureux, que le calife H\u00e2r\u00fbn ar-Rash\u00eed voulut qu&#8217;on lui amen\u00e2t la fille sans plus attendre, tant le d\u00e9sir qu&#8217;il avait d&#8217;elle \u00e9tait violent. Lorsqu&#8217;elle fut l\u00e0, il dit au cadi Ab\u00fb Y\u00fbsuf : <br>&#8211; Je veux lui faire l&#8217;amour tout de suite, je ne peux pas attendre la fin du d\u00e9lai l\u00e9gal d&#8217;abstinence, je n&#8217;en peux plus. Comment faire?<br>&#8211; Amenez, dit Abu Yusuf, l&#8217;un des esclaves du Commandeur des croyants, non encore affranchi s&#8217;entend. <br>L&#8217;esclave pr\u00e9sent\u00e9, Ab\u00fb Yusuf demanda permission de le marier \u00e0 la fille; il suffisait ensuite que l&#8217;esclave, avant m\u00eame de la toucher, la r\u00e9pudi\u00e2t; le calife serait alors libre de la poss\u00e9der sur l&#8217;heure et sans autre d\u00e9lai. Ce second avis enchanta le calife plus encore que le pr\u00e9c\u00e9dent.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e2r\u00fbn ar-Rashid veut une esclave de son calife. Ils d\u00e9cident de la partager. Puis H\u00e2r\u00fbn veut la poss\u00e9der tout de suite et ceci est arrang\u00e9 en jouant avec les lois et les r\u00e8glements et la mariant \u00e0 un esclave non affranchi. Mais cet esclave refusant ensuite de r\u00e9pudier la jeune esclave convoit\u00e9e, un autre tour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[111,128,21],"class_list":["post-10276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-mille-et-une-nuits","tag-abuse","tag-entitlement","tag-sex"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2022\/08\/jyoti-singh-kU-emVvRYIE-unsplash-scaled.jpg?fit=1707%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/10276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=10276"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/10276\/revisions"}],"predecessor-version":[{"id":10315,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/10276\/revisions\/10315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/10277"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=10276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=10276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=10276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}