{"id":11466,"date":"2022-11-22T11:42:25","date_gmt":"2022-11-22T10:42:25","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=11466"},"modified":"2022-12-11T11:47:40","modified_gmt":"2022-12-11T10:47:40","slug":"conte-des-amants-de-banu-udhra-nuits-688-a-691","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2022\/11\/22\/conte-des-amants-de-banu-udhra-nuits-688-a-691\/","title":{"rendered":"Conte des amants de Ban\u00fb &#8216;Udhra &#8211; Nuits 688 \u00e0 691"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jam\u00eel rencontre, seul au milieu du d\u00e9sert, un jeune homme qui lui explique qu&#8217;il attend tous les soirs sa cousine bien-aim\u00e9e qui a d\u00fb en marier un autre. Jam\u00eel propose au jeune homme d&#8217;attendre le soir et de partir avec sa bien-aim\u00e9e loin de son mari. Ce soir-l\u00e0, la jeune femme ne vient pas et le jeune homme part \u00e0 sa recherche. Elle s&#8217;est fait manger par un lion et le jeune homme en meurt d&#8217;amour. Jam\u00eel enterre les deux ensemble dans le d\u00e9sert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Apr\u00e8s avoir beaucoup pleur\u00e9, le jeune homme se retira un moment sous la tente, puis ressortit, soupira, hurla et, dans un sanglot, quitta ce monde. \u00c0 cette vue, je fus pris d&#8217;un tel d\u00e9sespoir, d&#8217;une telle d\u00e9solation que je faillis bien le suivre, tant j&#8217;\u00e9tais accabl\u00e9.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jam\u00eel rencontre, seul au milieu du d\u00e9sert, un jeune homme qui lui explique qu&#8217;il attend tous les soirs sa cousine bien-aim\u00e9e qui a d\u00fb en marier un autre. Jam\u00eel propose au jeune homme d&#8217;attendre le soir et de partir avec sa bien-aim\u00e9e loin de son mari. Ce soir-l\u00e0, la jeune femme ne vient pas et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11467,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[56,148,19],"class_list":["post-11466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-mille-et-une-nuits","tag-death","tag-fate","tag-love"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2022\/11\/shutterstock_78490540-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=11466"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11466\/revisions"}],"predecessor-version":[{"id":11651,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11466\/revisions\/11651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/11467"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=11466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=11466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=11466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}