{"id":11675,"date":"2022-12-13T09:19:44","date_gmt":"2022-12-13T08:19:44","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=11675"},"modified":"2024-11-04T21:20:35","modified_gmt":"2024-11-04T20:20:35","slug":"le-malade-imaginaire-moliere-1673","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2022\/12\/13\/le-malade-imaginaire-moliere-1673\/","title":{"rendered":"Le malade imaginaire &#8211; Moli\u00e8re (1673)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Faut-il r\u00e9sumer le Malade imaginaire ? Un homme qui se croit malade, entour\u00e9 d&#8217;une femme qui n&#8217;esp\u00e8re que sa mort pour h\u00e9riter de sa fortune, de sa fille qui l&#8217;adore qu&#8217;il veut marier \u00e0 un m\u00e9decin et de son fr\u00e8re qui arrivera \u00e0 lui faire entendre raison avec l&#8217;aide de Toinette la servante. Quelques quiproquos, de l&#8217;humour, de tr\u00e8s jolies tirades et le tour est jou\u00e9. Cette r\u00e9alisation au Th\u00e9\u00e2tre de Carouge est jou\u00e9e de fa\u00e7on plut\u00f4t traditionnelle, dans l&#8217;\u00e9poque, sauf peut-\u00eatre l&#8217;habillement de Toinette, pantalon noir et chemise verte vive en viscose, ce vert que l&#8217;on n&#8217;ose mettre sur une sc\u00e8ne depuis que Moli\u00e8re est mort dans cette couleur lors de la quatri\u00e8me repr\u00e9sentation du Malade imaginaire justement. \u00c0 noter l&#8217;apparition de la petite s\u0153ur qui n&#8217;est autre que la grande s\u0153ur qui joue \u00e0 genou. Hilarant.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Plus, dudit jour, un bon clyst\u00e8re d\u00e9tersif, compos\u00e9 avec catholicon double, rhubarbe, miel rosat,<br \/>et autres, suivant l\u2019ordonnance, pour balayer, laver et nettoyer le bas-ventre de Monsieur, trente sols.&#8221; Avec votre permission, dix sols. &#8220;Plus, dudit jour, le soir, un julep h\u00e9patique, soporatif et somnif\u00e8re, compos\u00e9 pour faire dormir Monsieur, trente-cinq sols.&#8221; Je ne me plains pas de celui-l\u00e0, car il me fit bien dormir. Dix, quinze, seize et dix-sept sols, six deniers. &#8220;Plus, du vingt-cinqui\u00e8me, une bonne m\u00e9decine purgative et corroborative, compos\u00e9e de casse r\u00e9cente avec s\u00e9n\u00e9 levantin, et autres, suivant l\u2019ordonnance de Monsieur Purgon, pour expulser et \u00e9vacuer la bile de Monsieur, quatre livres.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faut-il r\u00e9sumer le Malade imaginaire ? Un homme qui se croit malade, entour\u00e9 d&#8217;une femme qui n&#8217;esp\u00e8re que sa mort pour h\u00e9riter de sa fortune, de sa fille qui l&#8217;adore qu&#8217;il veut marier \u00e0 un m\u00e9decin et de son fr\u00e8re qui arrivera \u00e0 lui faire entendre raison avec l&#8217;aide de Toinette la servante. Quelques quiproquos, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[266],"tags":[111,208,19],"class_list":["post-11675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-theatre-de-carouge","tag-abuse","tag-illness","tag-love"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2022\/12\/alexander-grey-vgLTTWPesg-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=11675"}],"version-history":[{"count":5,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11675\/revisions"}],"predecessor-version":[{"id":11701,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11675\/revisions\/11701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/11678"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=11675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=11675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=11675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}