{"id":11863,"date":"2023-01-03T13:28:35","date_gmt":"2023-01-03T12:28:35","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=11863"},"modified":"2024-03-13T10:24:07","modified_gmt":"2024-03-13T09:24:07","slug":"avatar-james-cameron-2009","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2023\/01\/03\/avatar-james-cameron-2009\/","title":{"rendered":"Avatar &#8211; James Cameron (2009)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nous sommes en 2154 sur Pandora, une plan\u00e8te qui abrite dans son sous-sol de l&#8217;unobtanium, un minerai qui pourrait r\u00e9gler les probl\u00e8mes d&#8217;\u00e9nergie de la Terre. Sur Pandora habitent aussi les Na&#8217;vis, un peuple qui vit en symboise avec la nature et dont font partie les Omaticayas. Ceux-ci vivent dans leur arbre-maison, sous lequel justement se trouve le plus gros gisement d&#8217;unobtanium. Pour amadouer les Na&#8217;vis, les Terriens ont cr\u00e9\u00e9 des avatars de Na&#8217;vi qui contiennent le bagage g\u00e9n\u00e9tique d&#8217;un humain. Au travers d&#8217;un caisson, l&#8217;humain mis au repos p\u00e9n\u00e8tre ce corps de Na&#8217;vi. Jack Sully va replacer son fr\u00e8re jumeau dans son avatar apr\u00e8s que celui-ci ait \u00e9t\u00e9 assassin\u00e9. La suite de l&#8217;histoire est assez pr\u00e9visible. Jack s&#8217;enamourache de Neytiri, une Na&#8217;vi, et arrive \u00e0 devenir un Omaticaya \u00e0 part enti\u00e8re. Les militaires du programme en ont assez d&#8217;attendre que les Omaticayas veuillent bien quitter leur arbre et donc attaquent et d\u00e9truisent l&#8217;arbre. Mais Jack viendra en sauveur&#8230; Le num\u00e9ro deux \u00e9tant sorti, il fallait bien regarder le premier. M\u00eame si le sc\u00e9nario est un peu convenu, \u00e7a reste un joli film avec cette population bleue, ces animaux fantastiques et cette forte connexion avec la nature. Un film de 2h40 qui passe tr\u00e8s vite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Voil\u00e0 pourquoi je d\u00e9teste les Marines : ils nous pissent dessus sans m\u00eame essayer de nous faire croire qu&#8217;il pleut !&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-colibri-color-4-color\">Version originale en anglais &#8211; Regard\u00e9 en fran\u00e7ais<\/mark><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes en 2154 sur Pandora, une plan\u00e8te qui abrite dans son sous-sol de l&#8217;unobtanium, un minerai qui pourrait r\u00e9gler les probl\u00e8mes d&#8217;\u00e9nergie de la Terre. Sur Pandora habitent aussi les Na&#8217;vis, un peuple qui vit en symboise avec la nature et dont font partie les Omaticayas. Ceux-ci vivent dans leur arbre-maison, sous lequel justement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11864,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[215],"tags":[128,28,173],"class_list":["post-11863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films-2023","tag-entitlement","tag-nature","tag-war"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/01\/jeremy-bishop-EwKXn5CapA4-unsplash-scaled.jpg?fit=1707%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=11863"}],"version-history":[{"count":2,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11863\/revisions"}],"predecessor-version":[{"id":15109,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/11863\/revisions\/15109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/11864"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=11863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=11863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=11863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}