{"id":12230,"date":"2023-09-04T13:44:57","date_gmt":"2023-09-04T11:44:57","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=12230"},"modified":"2023-09-12T15:30:49","modified_gmt":"2023-09-12T13:30:49","slug":"conte-de-qamar-az-zaman-et-de-la-femme-du-joailler-nuits-963-a-978","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2023\/09\/04\/conte-de-qamar-az-zaman-et-de-la-femme-du-joailler-nuits-963-a-978\/","title":{"rendered":"Conte de Qamar az-Zam\u00e2n et de la femme du joailler &#8211; Nuits 963 \u00e0 978"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Qamar az-Zam\u00e2n est un jeune homme magnifique qui se prend d&#8217;amour pour la femme du joailler. Apr\u00e8s mille ruses, il r\u00e9ussit \u00e0 se faire ami du joailler et inviter chez lui. La femme du joailler tombe amoureuse imm\u00e9diatement. Qamar az-Zam\u00e2n et la femme du joaillier trouvent encore mille autres ruses pour duper le joailler et se sauver avec sa fortune. Rentr\u00e9 chez lui cependant, le p\u00e8re de Qamar az-Zam\u00e2n refuse qu&#8217;il marie la femme du joailler et enferme celle-ci avec ses servantes. Le joailler retrouve finalement Qamar az-Zam\u00e2n, est accueilli par le p\u00e8re de celui-ci \u00e0 bras ouverts et, gr\u00e2ce \u00e0 celui-ci, ira tuer sa perfide femme. Voil\u00e0 une jolie histoire de mensonges et de cocufiage o\u00f9 un seul des protagonistes est puni par la mort alors que l&#8217;autre s&#8217;en sort sans encombre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Et \u00e0 qui, cette pierre? &#8211; A un jeune marchand, tr\u00e8s beau, avec des yeux qui vous assassinent, des joues qui vous br\u00fblent, une bouche pareille \u00e0 l&#8217;anneau de Salomon, des pommettes comme des an\u00e9mones, des l\u00e8vres aussi rouges que corail, un cou de gazelle. Il a un teint blanc nuanc\u00e9 de rose, il est charmant et g\u00e9n\u00e9reux.&#8221; Et le joaillier de raconter comment Qamar az-Zam\u00e2n s&#8217;\u00e9tait comport\u00e9, de revenir tant\u00f4t sur sa beaut\u00e9 et sa gr\u00e2ce, tant\u00f4t sur sa g\u00e9n\u00e9rosit\u00e9 et ses mani\u00e8res exemplaires. Il insista tellement sur ces qualit\u00e9s qu&#8217;il rendit son \u00e9pouse amoureuse du gar\u00e7on, tant il est vrai que, pour faire un cocu, rien ne vaut un homme qui se met en t\u00eate de parler \u00e0 sa femme de la beaut\u00e9 d&#8217;un tel, de sa gr\u00e2ce et de son extr\u00eame g\u00e9n\u00e9rosit\u00e9 en mati\u00e8re d&#8217;argent.&#8221;<\/em><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qamar az-Zam\u00e2n est un jeune homme magnifique qui se prend d&#8217;amour pour la femme du joailler. Apr\u00e8s mille ruses, il r\u00e9ussit \u00e0 se faire ami du joailler et inviter chez lui. La femme du joailler tombe amoureuse imm\u00e9diatement. Qamar az-Zam\u00e2n et la femme du joaillier trouvent encore mille autres ruses pour duper le joailler et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11929,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[86,85,19],"class_list":["post-12230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-mille-et-une-nuits","tag-betrayal","tag-infidelity","tag-love"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/01\/shutterstock_83136580-scaled.jpg?fit=2560%2C1704&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=12230"}],"version-history":[{"count":5,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12230\/revisions"}],"predecessor-version":[{"id":13500,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12230\/revisions\/13500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/11929"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=12230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=12230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=12230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}