{"id":12347,"date":"2023-03-16T10:01:51","date_gmt":"2023-03-16T09:01:51","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=12347"},"modified":"2024-03-06T19:34:17","modified_gmt":"2024-03-06T18:34:17","slug":"la-conquete-de-la-terre-par-les-chats-alberto-montt-2022","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2023\/03\/16\/la-conquete-de-la-terre-par-les-chats-alberto-montt-2022\/","title":{"rendered":"La conqu\u00eate de la Terre par les chats &#8211; Alberto Montt (2022)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dieu est un chat qui a cr\u00e9\u00e9 des \u00eatres \u00e0 son image pour prendre possession de la Terre. Il faut bien se poser la question une fois : pourquoi est-on si facilement conquis pas ces b\u00eates qui sont, somme toute, paresseuses, \u00e9go\u00efstes et passablement destructrices. Difficile \u00e0 expliquer si ce n&#8217;est que nous avons \u00e9t\u00e9  hypnotis\u00e9s et avons subi un lavage de cerveau. Bref, une petite description du chat dans l&#8217;histoire, avec des interludes d\u00e9lirants sur, par exemple, l&#8217;amour des chats pour les bo\u00eetes. Un livre pour les vrais hypnotis\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;S&#8217;il \u00e9tait ch\u00e9ri par la soci\u00e9t\u00e9 chinoise et le bouddhisme, le chat fut tout de m\u00eame  banni du groupe sacr\u00e9 des animaux du zodiaque. La l\u00e9gende raconte qu&#8217;il fut puni par Bouddha qui avait appel\u00e9 tous les animaux aupr\u00e8s de lui. Le chat ne vint pas car il s&#8217;\u00e9tait endormi.&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-colibri-color-4-color\">Titre original : La conquista de los gatos<br>Traduit de l&#8217;espagnol<\/mark><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"827\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/03\/PXL_20230320_152036518_2-1.jpg?resize=1024%2C827&#038;ssl=1\" alt=\"\" class=\"wp-image-12383\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/03\/PXL_20230320_152036518_2-1-scaled.jpg?resize=1024%2C827&amp;ssl=1 1024w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/03\/PXL_20230320_152036518_2-1-scaled.jpg?resize=300%2C242&amp;ssl=1 300w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/03\/PXL_20230320_152036518_2-1-scaled.jpg?resize=768%2C620&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/03\/PXL_20230320_152036518_2-1-scaled.jpg?resize=1536%2C1240&amp;ssl=1 1536w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/03\/PXL_20230320_152036518_2-1-scaled.jpg?resize=2048%2C1653&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Dieu est un chat qui a cr\u00e9\u00e9 des \u00eatres \u00e0 son image pour prendre possession de la Terre. Il faut bien se poser la question une fois : pourquoi est-on si facilement conquis pas ces b\u00eates qui sont, somme toute, paresseuses, \u00e9go\u00efstes et passablement destructrices. Difficile \u00e0 expliquer si ce n&#8217;est que nous avons \u00e9t\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12381,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[213,216],"tags":[108,112,47],"class_list":["post-12347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chaellenge-riquiqui-2023","category-graphic-2023","tag-cats","tag-history","tag-humour"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/03\/jari-hytonen-YCPkW_r_6uA-unsplash-scaled.jpg?fit=2560%2C1712&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=12347"}],"version-history":[{"count":5,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12347\/revisions"}],"predecessor-version":[{"id":14909,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12347\/revisions\/14909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/12381"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=12347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=12347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=12347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}