{"id":12792,"date":"2023-05-29T20:24:38","date_gmt":"2023-05-29T18:24:38","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=12792"},"modified":"2023-06-17T09:14:05","modified_gmt":"2023-06-17T07:14:05","slug":"la-litterature-une-infographie-alexandre-gefan-guillemette-crozet-2022","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2023\/05\/29\/la-litterature-une-infographie-alexandre-gefan-guillemette-crozet-2022\/","title":{"rendered":"La litt\u00e9rature &#8211; Une infographie &#8211; Alexandre Gefan &#038; Guillemette Crozet (2022)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tout est dans le titre finalement. Une analyse de la litt\u00e9rature par des images, des repr\u00e9sentations. Soit sous l&#8217;angle de donn\u00e9es ext\u00e9rieures aux livres, comme l&#8217;histoire de la litt\u00e9rature, les livres ou auteurs les plus traduits, la proportion de femmes dans la litt\u00e9rature, soit des statistiques internes aux livres, les plus grandes phrases, le nombre et le lien entre les personnages. Bref, une quarantaine de graphes, de dessins, de sch\u00e9mas qui d\u00e9cryptent l&#8217;\u00e9crit. Un livre que j&#8217;aimerais garder en permanence sur ma table de nuit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Si la premi\u00e8re phrase d&#8217;\u00c0 la recherche du temps perdu de Proust est tr\u00e8s courte (&#8220;Longtemps je me suis couch\u00e9 de bonne heure&#8221; : 8 mots), l&#8217;\u00e9crivain a \u00e9t\u00e9 rendu c\u00e9l\u00e8bre par la longueur de ses phrases. La plus longue compte ainsi 931 mots, dans Sodome et Gomorrhe. Mais l&#8217;\u00e9tude statistique montre que Proust \u00e9crivait plut\u00f4t des phrases de plus en plus courtes au cours de son cycle.&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"842\" height=\"1024\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/05\/PXL_20230529_1526470322.jpg?resize=842%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-12796\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/05\/PXL_20230529_1526470322-scaled.jpg?resize=842%2C1024&amp;ssl=1 842w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/05\/PXL_20230529_1526470322-scaled.jpg?resize=247%2C300&amp;ssl=1 247w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/05\/PXL_20230529_1526470322-scaled.jpg?resize=768%2C935&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/05\/PXL_20230529_1526470322-scaled.jpg?resize=1262%2C1536&amp;ssl=1 1262w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/05\/PXL_20230529_1526470322-scaled.jpg?resize=1683%2C2048&amp;ssl=1 1683w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/05\/PXL_20230529_1526470322-scaled.jpg?w=2000&amp;ssl=1 2000w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Tout est dans le titre finalement. Une analyse de la litt\u00e9rature par des images, des repr\u00e9sentations. Soit sous l&#8217;angle de donn\u00e9es ext\u00e9rieures aux livres, comme l&#8217;histoire de la litt\u00e9rature, les livres ou auteurs les plus traduits, la proportion de femmes dans la litt\u00e9rature, soit des statistiques internes aux livres, les plus grandes phrases, le nombre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12871,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[214],"tags":[121,67,112],"class_list":["post-12792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books-2023","tag-books","tag-creativity","tag-history"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/06\/shutterstock_1979881058-scaled.jpg?fit=2560%2C1966&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=12792"}],"version-history":[{"count":7,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12792\/revisions"}],"predecessor-version":[{"id":12802,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12792\/revisions\/12802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/12871"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=12792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=12792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=12792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}