{"id":12852,"date":"2023-06-15T02:13:39","date_gmt":"2023-06-15T00:13:39","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=12852"},"modified":"2024-01-28T22:51:21","modified_gmt":"2024-01-28T21:51:21","slug":"basquiat-x-warhol-a-quatre-mains-fondation-louis-vuitton-paris-20239","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2023\/06\/15\/basquiat-x-warhol-a-quatre-mains-fondation-louis-vuitton-paris-20239\/","title":{"rendered":"Basquiat X Warhol, \u00c0 Quatre Mains &#8211; Fondation Louis Vuitton &#8211; Paris (2023)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Une collaboration de moins de deux ans de 1983 \u00e0 1985 et autour des 160 \u0153uvres communes. Dr\u00f4le de rencontre entre deux artistes que deux d\u00e9cennies s\u00e9parent. Une vraie \u0153uvre \u00e0 quatre mains, l&#8217;un cr\u00e9e puis l&#8217;autre intervient par-dessus puis le premier reprend l&#8217;\u0153uvre. Difficile parfois de comprendre qui a fait quoi. C&#8217;est assez indescriptible, souvent fouillis, avec parfois un air d&#8217;inachev\u00e9. Il y a aussi une s\u00e9rie de portraits noir-blanc des deux artistes en boxeurs, tr\u00e8s touchants. Tr\u00e8s belle exposition dans la structure exceptionnelle de la Fondation Louis-Vuitton. \u00c7a vaut la peine d&#8217;aller juste voir le b\u00e2timent. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;T\u00e9moin de leur amiti\u00e9 et de cette production commune, Keith Haring (1958-1990) parlera d&#8217;une \u00abconversation advenant par la peinture, \u00e0 la place des mots\u00a0\u00bb, et de deux esprits fusionnant pour en cr\u00e9er un\u00a0\u00abtroisi\u00e8me, s\u00e9par\u00e9 et unique\u00bb&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une collaboration de moins de deux ans de 1983 \u00e0 1985 et autour des 160 \u0153uvres communes. Dr\u00f4le de rencontre entre deux artistes que deux d\u00e9cennies s\u00e9parent. Une vraie \u0153uvre \u00e0 quatre mains, l&#8217;un cr\u00e9e puis l&#8217;autre intervient par-dessus puis le premier reprend l&#8217;\u0153uvre. Difficile parfois de comprendre qui a fait quoi. C&#8217;est assez indescriptible, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12957,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[117],"tags":[67,36,51],"class_list":["post-12852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exhibitions","tag-creativity","tag-friendship","tag-identity"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/07\/PXL_20230615_142119013.MP_-scaled-e1688314662814.jpg?fit=1484%2C748&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=12852"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12852\/revisions"}],"predecessor-version":[{"id":14415,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/12852\/revisions\/14415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/12957"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=12852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=12852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=12852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}