{"id":13172,"date":"2023-07-22T00:30:13","date_gmt":"2023-07-21T22:30:13","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=13172"},"modified":"2023-07-23T09:55:22","modified_gmt":"2023-07-23T07:55:22","slug":"zai-zai-zai-zai-francois-desagnat-2020","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2023\/07\/22\/zai-zai-zai-zai-francois-desagnat-2020\/","title":{"rendered":"Za\u00ef za\u00ef za\u00ef za\u00ef &#8211; Fran\u00e7ois Desagnat (2020)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un matin comme les autres, Fabrice va faire ses courses. Arriv\u00e9 \u00e0 la caisse, la caissi\u00e8re lui demande sa carte de fid\u00e9lit\u00e9&#8230; Il ne l&#8217;a pas. Le vigile du supermarch\u00e9 veut arr\u00eater Fabrice, mais en brandissant son poireau, celui-ci arrive \u00e0 s&#8217;\u00e9chapper et devient d\u00e8s lors un hors-la-loi en cavale. De rencontres loufoques en situations absurdes, il sera finalement arr\u00eat\u00e9, jug\u00e9 et &#8230; et bien personne ne sait, car personne n&#8217;a entendu la sentence lue par la juge. Tr\u00e8s fid\u00e8le \u00e0 la <a href=\"https:\/\/redheadwithabrain.ch\/index.php\/2021\/09\/25\/zai-zai-zai-zai-fabcaro-2015\/\">bande dessin\u00e9e de Fabcaro<\/a>, c&#8217;est bien film\u00e9, dr\u00f4le et absurde, juste ce qu&#8217;il faut. Un petit moment de plaisir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;C&#8217;est fou, hein, comme la vie est un long chemin d&#8217;o\u00f9 partent plusieurs petits chemins et suivant le chemin que tu prends, ben t&#8217;arrives ailleurs que l\u00e0 o\u00f9 tu serais arriv\u00e9 si tu avais pris un autre chemin. Tu trouves pas ?&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un matin comme les autres, Fabrice va faire ses courses. Arriv\u00e9 \u00e0 la caisse, la caissi\u00e8re lui demande sa carte de fid\u00e9lit\u00e9&#8230; Il ne l&#8217;a pas. Le vigile du supermarch\u00e9 veut arr\u00eater Fabrice, mais en brandissant son poireau, celui-ci arrive \u00e0 s&#8217;\u00e9chapper et devient d\u00e8s lors un hors-la-loi en cavale. De rencontres loufoques en situations [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13174,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[215],"tags":[133,178,48],"class_list":["post-13172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films-2023","tag-derision","tag-dystopia","tag-weirdness"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/07\/nrd-D6Tu_L3chLE-unsplash-scaled.jpg?fit=2560%2C1920&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=13172"}],"version-history":[{"count":1,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13172\/revisions"}],"predecessor-version":[{"id":13175,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13172\/revisions\/13175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/13174"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=13172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=13172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=13172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}