{"id":13752,"date":"2023-10-29T16:16:00","date_gmt":"2023-10-29T15:16:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=13752"},"modified":"2023-11-19T08:00:09","modified_gmt":"2023-11-19T07:00:09","slug":"zombillenium-tome-1-gretchen-arthur-de-pins-2011","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2023\/10\/29\/zombillenium-tome-1-gretchen-arthur-de-pins-2011\/","title":{"rendered":"Zombillenium &#8211; Tome 1. Gretchen &#8211; Arthur de Pins (2011)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aur\u00e9lien vient de se faire embaucher, un peu contre son gr\u00e9, au Zombillenium, un parc d&#8217;attraction avec de vrais zombies, squelettes, vampires, loups-garous et autres. Il est coach\u00e9 les premiers jours par Gretchen, la jolie sorci\u00e8re. Progressivement, Aur\u00e9lien devient un impressionnant vampire qui fait bien trembler les visiteurs du parc, surtout l&#8217;homme avec lequel sa femme l&#8217;a tromp\u00e9. Un premier volume de rencontre avec les personnages et de mise en place du d\u00e9cor, mais Gretchen cache quelque chose. C&#8217;est dr\u00f4le et les dessins sont magnifiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;- Va mourir ! Mes bandages datent de 3000 ans avant JC. Je ne suis pas un cadavre ordinaire trouv\u00e9 dans une fosse commune !<br>&#8211; NaN mais, tu sais ce qu&#8217;y te dit le cadavre ordinaire ? Je suis le squelette d&#8217;un militant noir pacifiste mort sur la chaise \u00e9lectrique en Louisiane en 1956 !<br>&#8211; Sans blague ? T&#8217;es black ?&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"900\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_153347179.MP2_.jpg?resize=1024%2C900&#038;ssl=1\" alt=\"\" class=\"wp-image-13850\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_153347179.MP2_-scaled.jpg?resize=1024%2C900&amp;ssl=1 1024w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_153347179.MP2_-scaled.jpg?resize=300%2C264&amp;ssl=1 300w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_153347179.MP2_-scaled.jpg?resize=768%2C675&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_153347179.MP2_-scaled.jpg?resize=1536%2C1350&amp;ssl=1 1536w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_153347179.MP2_-scaled.jpg?resize=2048%2C1800&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Aur\u00e9lien vient de se faire embaucher, un peu contre son gr\u00e9, au Zombillenium, un parc d&#8217;attraction avec de vrais zombies, squelettes, vampires, loups-garous et autres. Il est coach\u00e9 les premiers jours par Gretchen, la jolie sorci\u00e8re. Progressivement, Aur\u00e9lien devient un impressionnant vampire qui fait bien trembler les visiteurs du parc, surtout l&#8217;homme avec lequel sa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13838,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[216],"tags":[56,47,48],"class_list":["post-13752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graphic-2023","tag-death","tag-humour","tag-weirdness"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/israel-palacio-P6FgiDNe6W4-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=13752"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13752\/revisions"}],"predecessor-version":[{"id":13856,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13752\/revisions\/13856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/13838"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=13752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=13752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=13752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}