{"id":13775,"date":"2023-11-02T22:00:07","date_gmt":"2023-11-02T21:00:07","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=13775"},"modified":"2023-11-15T18:20:00","modified_gmt":"2023-11-15T17:20:00","slug":"elles-tome-1-la-nouvelles-kid-toussaint-aveline-stokart-2021","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2023\/11\/02\/elles-tome-1-la-nouvelles-kid-toussaint-aveline-stokart-2021\/","title":{"rendered":"Elles &#8211; Tome 1. La nouvelle(s) &#8211; Kid Toussaint\u00a0&#038; Aveline Stokart (2021)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Une nouvelle fille arrive \u00e0 l&#8217;\u00e9cole, Elle. Plut\u00f4t jolie, plut\u00f4t gentille, elle est imm\u00e9diatement adopt\u00e9e par un groupe d&#8217;amis. Mais les choses ne se passent pas si facilement. Elle change d&#8217;humeur sans raison et devient ing\u00e9rable. Et qui est cet homme qui la suit dans la rue ? Ses amis l&#8217;entourent et tentent de l&#8217;aider \u00e0 percer les myst\u00e8res de sa vie. C&#8217;est tr\u00e8s mignon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Que de doutes ! Tu crois que tu auras les \u00e9paules assez solides pour encaisser tout cela Rosette ? La porte est encore ferm\u00e9e pour moi, je le sais&#8230; mais je peux continuer \u00e0 ouvrir les autres&#8230; et tu finiras par craquer.&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"747\" height=\"1024\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_1531268392.jpg?resize=747%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-13825\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_1531268392-scaled.jpg?resize=747%2C1024&amp;ssl=1 747w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_1531268392-scaled.jpg?resize=219%2C300&amp;ssl=1 219w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_1531268392-scaled.jpg?resize=768%2C1052&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_1531268392-scaled.jpg?resize=1121%2C1536&amp;ssl=1 1121w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_1531268392-scaled.jpg?resize=1495%2C2048&amp;ssl=1 1495w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/PXL_20231108_1531268392-scaled.jpg?w=1869&amp;ssl=1 1869w\" sizes=\"auto, (max-width: 747px) 100vw, 747px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Une nouvelle fille arrive \u00e0 l&#8217;\u00e9cole, Elle. Plut\u00f4t jolie, plut\u00f4t gentille, elle est imm\u00e9diatement adopt\u00e9e par un groupe d&#8217;amis. Mais les choses ne se passent pas si facilement. Elle change d&#8217;humeur sans raison et devient ing\u00e9rable. Et qui est cet homme qui la suit dans la rue ? Ses amis l&#8217;entourent et tentent de l&#8217;aider [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13793,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[216],"tags":[20,36,51],"class_list":["post-13775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graphic-2023","tag-adolescence","tag-friendship","tag-identity"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2023\/11\/priscilla-du-preez-9e4n5-xvvbg-unsplash-scaled-e1700070089534.jpg?fit=2560%2C1139&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=13775"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13775\/revisions"}],"predecessor-version":[{"id":13835,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/13775\/revisions\/13835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/13793"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=13775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=13775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=13775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}