{"id":14475,"date":"2024-02-11T20:45:23","date_gmt":"2024-02-11T19:45:23","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=14475"},"modified":"2024-03-02T08:30:22","modified_gmt":"2024-03-02T07:30:22","slug":"hetre-pourpre-kim-de-lhorizon-2023","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/02\/11\/hetre-pourpre-kim-de-lhorizon-2023\/","title":{"rendered":"H\u00eatre pourpre &#8211; Kim de l&#8217;Horizon (2023)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Enchev\u00eatrement de trajectoires, de spirales concentriques. Comprendre l&#8217;histoire du h\u00eatre pourpre plant\u00e9 par l&#8217;arri\u00e8re-grand-p\u00e8re, retrouver la lign\u00e9e des femmes de la famille pour contrecarrer la g\u00e9n\u00e9alogie des hommes, utiliser l&#8217;\u00e9crit comme exutoire de la peur, comme affirmation de soi. Ce livre est tout ceci \u00e0 la fois, comme une danse, un pas en avant, quelques pas en arri\u00e8re, une pirouette et \u00e7a repart. Le texte est magnifique, un peu d\u00e9cousu parfois, mais magnifique. Le texte change de langue et de police et, lu dans la traduction fran\u00e7aise, l&#8217;\u00e9criture est soigneusement non genr\u00e9e, et de fa\u00e7on originale. Une belle prouesse pour une auto-fiction prodigieuse. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;J&#8217;ai commenc\u00e9 ces textes dans l&#8217;id\u00e9e de fabriquer un chaudron, un chaudron \u00e0 care contenant toutes sortes de potions magiques. Je voulais gu\u00e9rir sans sauver au sens sacr\u00e9 du terme, sans rechercher l&#8217;harmonie, la puret\u00e9. Peut-\u00eatre ne s&#8217;agit-il pas tant de gu\u00e9rison que de cicatrisation, de ces stigmates qui se dessinent d&#8217;eux-m\u00eames sur la peau. Car je ne veux pas que la plaie se referme ni vu ni connu. Que l&#8217;absence s&#8217;oublie sans laisser de traces. Je ne veux pas d&#8217;un point qui cl\u00f4t la phrase, je veux un point-virgule qui dit : &#8220;Faisons une pause, mais n&#8217;en restons pas l\u00e0&#8221;, qui laisse la phrase s&#8217;\u00e9couler tout en pr\u00e9servant l&#8217;interstice entre ses deux signes &#8211; je veux continuer \u00e0 suivre cette spirale qui m&#8217;entra\u00eene autour du vide.&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-colibri-color-4-color\">Titre original : Blutbuch<br>Traduit du suisse allemand et de l&#8217;allemand (passages en anglais et en fran\u00e7ais)<\/mark><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enchev\u00eatrement de trajectoires, de spirales concentriques. Comprendre l&#8217;histoire du h\u00eatre pourpre plant\u00e9 par l&#8217;arri\u00e8re-grand-p\u00e8re, retrouver la lign\u00e9e des femmes de la famille pour contrecarrer la g\u00e9n\u00e9alogie des hommes, utiliser l&#8217;\u00e9crit comme exutoire de la peur, comme affirmation de soi. Ce livre est tout ceci \u00e0 la fois, comme une danse, un pas en avant, quelques [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14482,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[255],"tags":[31,29,32],"class_list":["post-14475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books-2024","tag-family","tag-trees","tag-women"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/02\/04.jpg?fit=850%2C400&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=14475"}],"version-history":[{"count":7,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14475\/revisions"}],"predecessor-version":[{"id":14744,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14475\/revisions\/14744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/14482"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=14475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=14475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=14475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}