{"id":14928,"date":"2021-07-23T14:09:00","date_gmt":"2021-07-23T12:09:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=14928"},"modified":"2024-04-30T10:54:52","modified_gmt":"2024-04-30T08:54:52","slug":"le-sergent-recruteur-paris-2021","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/07\/23\/le-sergent-recruteur-paris-2021\/","title":{"rendered":"Le Sergent Recruteur &#8211; Paris (2021)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lors d&#8217;un week-end \u00e0 Paris, premier voyage \u00e0 l&#8217;\u00e9tranger depuis longtemps, Covid-19 oblige, nous sommes sortis pour une soir\u00e9e au Sergent Recruteur. Un nom \u00e9trange pour un restaurant, soit dit en passant. Leur site web ne donne pas d&#8217;historique du restaurant. Apparemment, il s&#8217;agissait d&#8217;une taverne, \u00e9tablie sur l&#8217;\u00eele, il y a longtemps. Le chef est Alain P\u00e9gouret, qui a commenc\u00e9 sa carri\u00e8re chez Jo\u00ebl Robuchon. L&#8217;accueil au restaurant est tendu, le ma\u00eetre d&#8217;h\u00f4tel ayant des reproches \u00e0 faire \u00e0 l&#8217;une des employ\u00e9es. Le sommelier devrait s&#8217;acheter une chemise un peu plus grande, pour qu&#8217;on ne voie pas son ventre \u00e0 chaque fois qu&#8217;il nous sert un verre, mais il est par ailleurs sympathique. La cuisine est bonne, mais presque trop pointilleuse, d\u00e9cor\u00e9e de carr\u00e9s de carottes de 2 mm de c\u00f4t\u00e9 en mosa\u00efque avec un autre l\u00e9gume, et tous les plats de cette fa\u00e7on. Bref, un peu trop. Heureusement, l&#8217;\u00eele Saint-Louis le soir est un endroit charmant et romantique pour une belle promenade apr\u00e8s le repas.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:15px\"><strong>Menu (accord mets et vin)<\/strong><br>Amuse-bouche<br>Mise en bouche<br>Truite iris\u00e9e au go\u00fbt l\u00e9g\u00e8rement fum\u00e9, cr\u00e8me fouett\u00e9e au sirop d&#8217;\u00e9rable, marmelade citron cardamone et condiments<br>Girolles juste saisies, lasagne et jaune d&#8217;\u0153uf \u00e0 peine coulant, relev\u00e9 par une \u00e9cume poulette &#8220;Yuzu&#8221; et craquelin<br>Noix de ris de veau dor\u00e9s au basilic, t\u00e9tragone et girolles en salade, poivrade saut\u00e9e<br>Cerises gourmandes sur un biscuit moelleux, au pain d&#8217;\u00e9pices. chantilly \u00e0 la fleur de sakura, glace au lait d&#8217;amande.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"232\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/04\/one-star-5.png?resize=225%2C232&#038;ssl=1\" alt=\"\" class=\"wp-image-15692\" style=\"width:48px;height:auto\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.lesergentrecruteur.fr\/\">Le Sergent Recruteur<\/a> &#8211; 41 Rue Saint-Louis en l\u2019\u00cele &#8211; 75004 Paris<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors d&#8217;un week-end \u00e0 Paris, premier voyage \u00e0 l&#8217;\u00e9tranger depuis longtemps, Covid-19 oblige, nous sommes sortis pour une soir\u00e9e au Sergent Recruteur. Un nom \u00e9trange pour un restaurant, soit dit en passant. Leur site web ne donne pas d&#8217;historique du restaurant. Apparemment, il s&#8217;agissait d&#8217;une taverne, \u00e9tablie sur l&#8217;\u00eele, il y a longtemps. Le chef [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14929,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[258],"tags":[252,93,48],"class_list":["post-14928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amazing-restaurants","tag-contempt","tag-food","tag-weirdness"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/03\/PXL_20210723_201632302-scaled.jpg?fit=2560%2C1920&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=14928"}],"version-history":[{"count":10,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14928\/revisions"}],"predecessor-version":[{"id":15701,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14928\/revisions\/15701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/14929"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=14928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=14928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=14928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}