{"id":14969,"date":"2024-03-09T12:52:17","date_gmt":"2024-03-09T11:52:17","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=14969"},"modified":"2024-03-09T12:52:48","modified_gmt":"2024-03-09T11:52:48","slug":"legere-et-court-vetue-antoine-jaquier-2017","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/03\/09\/legere-et-court-vetue-antoine-jaquier-2017\/","title":{"rendered":"L\u00e9g\u00e8re et court-v\u00eatue &#8211; Antoine Jaquier (2017)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">C&#8217;est l&#8217;histoire de M\u00e9lodie et Tom, un jeune couple branch\u00e9. Elle vit uniquement pour la mode, haute-couture, minceur et blog. Lui est photographe et joueur de poker qui y perd tout son argent \u00e0 intervalles r\u00e9guliers. Mais, tout compte fait, aucun des deux ne sait exactement qui il est et la recherche de cette identit\u00e9 va passer par des extr\u00eames dramatiques. Sexe sous toutes ses variantes, menaces et agressions, divorce et suicide, la liste est longue. Toute l&#8217;histoire est plac\u00e9e entre les attentats de Charlie Hebdo et ceux du Bataclan. C&#8217;est trash comme Jaquier aime, mais peut-\u00eatre plus facile, superficiel, que les autres romans que j&#8217;ai lus de cet auteur.<br><br><em>&#8220;T&#8217;es trop b\u00eate, dit Victoria, toi cass\u00e9 le gueule de M\u00e9lodie, Blerim va te tuer. Fallait pas toucher la fille, cette fois plus personne peut t&#8217;aider. Toi finir fond du lac avec pied de parasol autour du cou. Ou bien t&#8217;enfuir Am\u00e9rique, ou bien toi mort.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&#8217;est l&#8217;histoire de M\u00e9lodie et Tom, un jeune couple branch\u00e9. Elle vit uniquement pour la mode, haute-couture, minceur et blog. Lui est photographe et joueur de poker qui y perd tout son argent \u00e0 intervalles r\u00e9guliers. Mais, tout compte fait, aucun des deux ne sait exactement qui il est et la recherche de cette identit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14970,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[255],"tags":[133,177,139],"class_list":["post-14969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books-2024","tag-derision","tag-society","tag-wealth"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/03\/gio-gix-VbB3depebtI-unsplash-scaled.jpg?fit=1920%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=14969"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14969\/revisions"}],"predecessor-version":[{"id":14975,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/14969\/revisions\/14975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/14970"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=14969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=14969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=14969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}