{"id":15329,"date":"2022-05-07T11:26:00","date_gmt":"2022-05-07T09:26:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=15329"},"modified":"2024-04-11T15:11:52","modified_gmt":"2024-04-11T13:11:52","slug":"la-toupina-bordeaux-2022","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2022\/05\/07\/la-toupina-bordeaux-2022\/","title":{"rendered":"La Toupina &#8211; Bordeaux (2022)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Restaurant conseill\u00e9 par des amis parce que nous allions \u00e0 Bordeaux, petite soir\u00e9e \u00e0 la Tupina. La tupina, c&#8217;est le chaudron qui tr\u00f4ne au milieu de la chemin\u00e9e du restaurant. Un tr\u00e8s beau d\u00e9cor, des meubles anciens magnifiques, tr\u00e8s orn\u00e9, tr\u00e8s accueillant. Nous mangeons \u00e0 une table plac\u00e9e comme un petit balcon \u00e0 la fen\u00eatre, romantique \u00e0 souhait. Le restaurant propose des plats traditionnels du Sud-Ouest tels que foie gras, cassoulet et de superbes morceaux de viande. Nous avons m\u00eame go\u00fbt\u00e9 du caviar fran\u00e7ais. Tout \u00e9tait excellent, le personnel adorable. Une d\u00e9couverte qui nous a procur\u00e9 une grande joie. La prochaine fois, nous retournerons \u00e0 Bordeaux express\u00e9ment pour manger \u00e0 la Tupina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.latupina.com\/\">La Tupina<\/a> &#8211; 6 Rue Porte de la Monnaie &#8211; 33800 Bordeaux<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Restaurant conseill\u00e9 par des amis parce que nous allions \u00e0 Bordeaux, petite soir\u00e9e \u00e0 la Tupina. La tupina, c&#8217;est le chaudron qui tr\u00f4ne au milieu de la chemin\u00e9e du restaurant. Un tr\u00e8s beau d\u00e9cor, des meubles anciens magnifiques, tr\u00e8s orn\u00e9, tr\u00e8s accueillant. Nous mangeons \u00e0 une table plac\u00e9e comme un petit balcon \u00e0 la fen\u00eatre, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15333,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[258],"tags":[37,93,19],"class_list":["post-15329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-amazing-restaurants","tag-bliss","tag-food","tag-love"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/03\/tyler-nix-uQ4WTXwjRro-unsplash-scaled.jpg?fit=1707%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=15329"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15329\/revisions"}],"predecessor-version":[{"id":15569,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15329\/revisions\/15569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/15333"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=15329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=15329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=15329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}