{"id":15369,"date":"2024-03-28T12:36:31","date_gmt":"2024-03-28T11:36:31","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=15369"},"modified":"2024-03-28T12:57:32","modified_gmt":"2024-03-28T11:57:32","slug":"le-serpent-cosmique-jeremy-narby-1995","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/03\/28\/le-serpent-cosmique-jeremy-narby-1995\/","title":{"rendered":"Le serpent cosmique &#8211; Jeremy Narby (1995)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ce livre, plut\u00f4t r\u00e9cit autobiographique qu&#8217;essai formel, explore les liens entre la connaissance traditionnelle des peuples indig\u00e8nes de l&#8217;Amazonie et les d\u00e9couvertes de la science moderne, notamment entre les visions produites par les substances hallucinog\u00e8nes et l&#8217;ADN. Il s&#8217;appuie sur les t\u00e9moignages de chamans, qui racontent que les savoirs \u00e9labor\u00e9s de leurs peuples sur la nature, les plantes m\u00e9dicinales et la vie en g\u00e9n\u00e9ral pourraient \u00eatre issus de visions et d&#8217;exp\u00e9riences spirituelles provoqu\u00e9es par des psychotropes, particuli\u00e8rement de l&#8217;ayahuasca. Le serpent dans tout \u00e7a ? Souvent symbole de sagesse et de connaissance, cette vision r\u00e9currente pourrait refl\u00e9ter une compr\u00e9hension intuitive des processus biologiques fondamentaux, tels que l&#8217;ADN et l&#8217;\u00e9volution. Pas r\u00e9ellement une d\u00e9monstration scientifique, qui serait de toute fa\u00e7on impossible, mais un r\u00e9cit qui ouvre des petites fen\u00eatres dans nos id\u00e9es toutes faites. Intriguant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;D&#8217;autre part, les plantes ne communiquent pas, du moins pas comme les humains. Certes, une fleur transmet de l&#8217;information \u00e0 une abeille en \u00e9mettant son parfum. Mais les th\u00e9ories scientifiques de la communication consid\u00e8rent que seuls les \u00eatres humains emploient des symboles abstraits, comme des mots ou des images&#8221;. Les plantes ne relayent pas d&#8217;information par l&#8217;interm\u00e9diaire de signes abstraits prenant la forme d&#8217;images mentales. La science consid\u00e8re que le cerveau humain est la source des images hallucinatoires et que les plantes psychoactives ne font que d\u00e9clencher ces images par l&#8217;interm\u00e9diaire des mol\u00e9cules hallucinog\u00e8nes qu&#8217;elles contiennent.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce livre, plut\u00f4t r\u00e9cit autobiographique qu&#8217;essai formel, explore les liens entre la connaissance traditionnelle des peuples indig\u00e8nes de l&#8217;Amazonie et les d\u00e9couvertes de la science moderne, notamment entre les visions produites par les substances hallucinog\u00e8nes et l&#8217;ADN. Il s&#8217;appuie sur les t\u00e9moignages de chamans, qui racontent que les savoirs \u00e9labor\u00e9s de leurs peuples sur la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15370,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[255],"tags":[24,218,48],"class_list":["post-15369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books-2024","tag-magic","tag-science","tag-weirdness"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/03\/david-clode-JzQ71rPqeJA-unsplash-scaled.jpg?fit=1715%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=15369"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15369\/revisions"}],"predecessor-version":[{"id":15373,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15369\/revisions\/15373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/15370"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=15369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=15369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=15369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}