{"id":15484,"date":"2024-04-08T01:35:00","date_gmt":"2024-04-07T23:35:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=15484"},"modified":"2024-04-09T18:24:42","modified_gmt":"2024-04-09T16:24:42","slug":"le-voyage-de-shuna-hayao-miyazaki-1983","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/04\/08\/le-voyage-de-shuna-hayao-miyazaki-1983\/","title":{"rendered":"Le Voyage de Shuna &#8211; Hayao Miyazaki (1983)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Shuna vit dans une contr\u00e9e asiatique d\u00e9sertique, rien ne pousse, la vie est dure. Un jour, un \u00e9tranger arrive dans son village et, avant de mourir, explique \u00e0 Shuna qu&#8217;il doit d\u00e9couvrir les graines dor\u00e9es, qui permettront de nourrir son peuple. Shuna part en qu\u00eate, croise des villes qui font de la traite d&#8217;humains et arrive au pays des hommes-dieux et des graines dor\u00e9es, mais la qu\u00eate n&#8217;est pas termin\u00e9e&#8230; Joli emonogatari, r\u00e9cit illustr\u00e9 plut\u00f4t que manga, de Miyazaki avec ses th\u00e9matiques et son dessin typique. Une belle lecture.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Ils travaillaient d&#8217;arrache-pied puis ils mouraient&#8230; Triste et mis\u00e9rable \u00e9tait leur vie. Belle et impitoyable \u00e9tait la nature.&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"854\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/04\/PXL_20240408_0655279502-EDIT-1024x854.jpg?resize=1024%2C854&#038;ssl=1\" alt=\"\" class=\"wp-image-15487\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/04\/PXL_20240408_0655279502-EDIT-scaled.jpg?resize=1024%2C854&amp;ssl=1 1024w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/04\/PXL_20240408_0655279502-EDIT-scaled.jpg?resize=300%2C250&amp;ssl=1 300w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/04\/PXL_20240408_0655279502-EDIT-scaled.jpg?resize=768%2C641&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/04\/PXL_20240408_0655279502-EDIT-scaled.jpg?resize=1536%2C1281&amp;ssl=1 1536w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/04\/PXL_20240408_0655279502-EDIT-scaled.jpg?resize=2048%2C1708&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Shuna vit dans une contr\u00e9e asiatique d\u00e9sertique, rien ne pousse, la vie est dure. Un jour, un \u00e9tranger arrive dans son village et, avant de mourir, explique \u00e0 Shuna qu&#8217;il doit d\u00e9couvrir les graines dor\u00e9es, qui permettront de nourrir son peuple. Shuna part en qu\u00eate, croise des villes qui font de la traite d&#8217;humains et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[256],"tags":[59,24,62],"class_list":["post-15484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graphic-2024","tag-crime","tag-magic","tag-quest"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/04\/zura-narimanishvili-5iX4W5tIjYM-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=15484"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15484\/revisions"}],"predecessor-version":[{"id":15492,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15484\/revisions\/15492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/15485"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=15484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=15484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=15484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}