{"id":15839,"date":"2024-06-07T23:58:00","date_gmt":"2024-06-07T21:58:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=15839"},"modified":"2024-06-13T14:08:31","modified_gmt":"2024-06-13T12:08:31","slug":"pensees-profondes-anne-laure-reboul-regis-penet-2024","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/06\/07\/pensees-profondes-anne-laure-reboul-regis-penet-2024\/","title":{"rendered":"Pens\u00e9es profondes &#8211; Anne-Laure Reboul &amp; R\u00e9gis Penet (2024)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Louise est une jeune femme ravissante et intelligente&#8230; mais qui ne sait pas dire nom&#8230; \u00e0 son copain, \u00e0 sa soi-disant meilleure amie, finalement \u00e0 toute personne de son entourage. Elle se fait toujours pi\u00e9ger, s&#8217;emberlificote dans des petits mensonges, se plie aux d\u00e9sirs des autres et finit par renoncer \u00e0 ses d\u00e9sirs. Mais, c&#8217;est promis, elle va s&#8217;en sortir. Une bande dessin\u00e9e un peu l\u00e9g\u00e8re sur l&#8217;affirmation de soi, avec un beau dessin et des petites situations cocasses. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Cher Journal,<br>&#8220;Ce qui ne tue pas rend plus fort&#8221;, a dit Nietzsche,<br>&#8220;Le changement est d&#8217;abord un \u00e9tat d&#8217;esprit&#8221;, a dit Jacques Chirac.<br>Je dois garder en t\u00eate ces deux phrases inspirantes pour me sortir de ce qui me semble \u00eatre une bien mauvaise passe.<br>Je me rends compte que le chemin sera sem\u00e9 d&#8217;emb\u00fbches.<br>Ces deux mantras seront d&#8217;abord mes b\u00e9quilles, puis mes ailes.<br>Foi de Louise.&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"817\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/06\/PXL_20240613_115521202.MP2_.jpg?resize=1024%2C817&#038;ssl=1\" alt=\"\" class=\"wp-image-15862\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/06\/PXL_20240613_115521202.MP2_-scaled.jpg?resize=1024%2C817&amp;ssl=1 1024w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/06\/PXL_20240613_115521202.MP2_-scaled.jpg?resize=300%2C239&amp;ssl=1 300w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/06\/PXL_20240613_115521202.MP2_-scaled.jpg?resize=768%2C613&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/06\/PXL_20240613_115521202.MP2_-scaled.jpg?resize=1536%2C1226&amp;ssl=1 1536w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/06\/PXL_20240613_115521202.MP2_-scaled.jpg?resize=2048%2C1634&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Louise est une jeune femme ravissante et intelligente&#8230; mais qui ne sait pas dire nom&#8230; \u00e0 son copain, \u00e0 sa soi-disant meilleure amie, finalement \u00e0 toute personne de son entourage. Elle se fait toujours pi\u00e9ger, s&#8217;emberlificote dans des petits mensonges, se plie aux d\u00e9sirs des autres et finit par renoncer \u00e0 ses d\u00e9sirs. Mais, c&#8217;est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15854,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[256],"tags":[51,98,19],"class_list":["post-15839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graphic-2024","tag-identity","tag-life","tag-love"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/06\/phil-hearing-U7PitHRnTNU-unsplash-scaled.jpg?fit=1708%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=15839"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15839\/revisions"}],"predecessor-version":[{"id":15865,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15839\/revisions\/15865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/15854"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=15839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=15839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=15839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}