{"id":15879,"date":"2024-06-15T07:33:00","date_gmt":"2024-06-15T05:33:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=15879"},"modified":"2024-06-16T17:19:44","modified_gmt":"2024-06-16T15:19:44","slug":"nous-nous-verrons-en-aout-gabriel-garcia-marquez-2024","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/06\/15\/nous-nous-verrons-en-aout-gabriel-garcia-marquez-2024\/","title":{"rendered":"Nous nous verrons en ao\u00fbt &#8211; Gabriel Garc\u00eda M\u00e1rquez (2024)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ana Magdalena Bach est une femme \u00e9panouie et heureuse en couple. Chaque ann\u00e9e, au mois d&#8217;ao\u00fbt, elle rend visite \u00e0 la tombe de sa m\u00e8re enterr\u00e9e sur une \u00eele, dort sur place et rentre le lendemain. Mais, une ann\u00e9e, elle se laisse s\u00e9duire et passe une nuit torride avec un inconnu, les ann\u00e9es suivantes aussi jusqu&#8217;\u00e0 l&#8217;exhumation de sa m\u00e8re. Vraiment pas un tr\u00e8s bon Garc\u00eda M\u00e1rquez \u00e0 mon go\u00fbt, qu&#8217;il ne voulait d&#8217;ailleurs pas que ses h\u00e9ritiers publient. C&#8217;est plus que l\u00e9ger, il y a une multitude de petites pistes qui ne sont pas suivies et une fin presque brutale. De cet \u00e9crivain, je gardais le souvenir d&#8217;une \u00e9criture plus riche et plus fine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Elle fut stup\u00e9faite par la ma\u00eetrise de magicien de salon avec laquelle il la d\u00e9nuda du bout des doigts, pi\u00e8ce de v\u00eatement apr\u00e8s pi\u00e8ce de v\u00eatement, comme s&#8217;il pelait un oignon. Au premier assaut, elle crut mourir de douleur et d&#8217;une commotion atroce de g\u00e9nisse \u00e9cartel\u00e9e. Elle en resta souffle coup\u00e9, couverte d&#8217;une sueur glac\u00e9e, mais en appela \u00e0 ses instincts primaires pour ne pas se sentir amoindrie ni porter \u00e0 croire qu&#8217;elle demeurait en reste avec lui et ils se livr\u00e8rent ensemble au plaisir inconcevable de la force bestiale subjugu\u00e9e par la douceur.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ana Magdalena Bach est une femme \u00e9panouie et heureuse en couple. Chaque ann\u00e9e, au mois d&#8217;ao\u00fbt, elle rend visite \u00e0 la tombe de sa m\u00e8re enterr\u00e9e sur une \u00eele, dort sur place et rentre le lendemain. Mais, une ann\u00e9e, elle se laisse s\u00e9duire et passe une nuit torride avec un inconnu, les ann\u00e9es suivantes aussi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15881,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[255],"tags":[82,85,19],"class_list":["post-15879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books-2024","tag-grief","tag-infidelity","tag-love"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/06\/orion-m_T5fWmYSWw-unsplash-scaled.jpg?fit=2560%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=15879"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15879\/revisions"}],"predecessor-version":[{"id":15885,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/15879\/revisions\/15885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/15881"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=15879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=15879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=15879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}