{"id":16135,"date":"2024-08-16T12:54:55","date_gmt":"2024-08-16T10:54:55","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=16135"},"modified":"2024-08-21T23:17:00","modified_gmt":"2024-08-21T21:17:00","slug":"pista-nera-antonio-manzini-2013","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/08\/16\/pista-nera-antonio-manzini-2013\/","title":{"rendered":"Pista nera &#8211; Antonio Manzini (2013)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Questo \u00e8 il primo romanzo che vede protagonista il vice commissario di polizia Rocco Schiavone. Ambientato in un piccolo paese nella Valle d&#8217;Aosta, la storia inizia con il ritrovamento di un cadavere su una pista da sci nera. Schiavone, un detective romano burbero e anticonvenzionale, viene incaricato di indagare. Mentre si muove all&#8217;interno di una comunit\u00e0 chiusa e insulare, Schiavone scopre segreti, tensioni locali e motivi nascosti, mentre affronta il proprio passato travagliato. Ho amato il personaggio di Schiavone, l&#8217;arguzia sardonica e i metodi poco ortodossi, nonch\u00e9 la freschezza e la semplicit\u00e0 dell&#8217;indagine. Sono sicura che torner\u00f2 a leggere questo commissario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Camminava verso la grande costruzione che serviva da garage per i mezzi cingolati in fondo alla quale, dietro a una porta a vetri, c&#8217;era la scuola di sci. Donne imbacuccate in pelliccia se ne stavano sedute ad aspettare i figli sciatori. Somigliavano a delle tartarughe, con la testa quasi interamente infilata nel carapace peloso e le mani in tasca. Ai piedi sembrava avessero dei fox terrier abbracciati alle caviglie.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo \u00e8 il primo romanzo che vede protagonista il vice commissario di polizia Rocco Schiavone. Ambientato in un piccolo paese nella Valle d&#8217;Aosta, la storia inizia con il ritrovamento di un cadavere su una pista da sci nera. Schiavone, un detective romano burbero e anticonvenzionale, viene incaricato di indagare. Mentre si muove all&#8217;interno di una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16185,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[255],"tags":[59,133,47],"class_list":["post-16135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books-2024","tag-crime","tag-derision","tag-humour"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/08\/urlaubstracker-TR77ZpydMgQ-unsplash-scaled.jpg?fit=2560%2C1440&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=16135"}],"version-history":[{"count":6,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16135\/revisions"}],"predecessor-version":[{"id":16210,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16135\/revisions\/16210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/16185"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=16135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=16135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=16135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}