{"id":16424,"date":"2024-09-20T10:08:00","date_gmt":"2024-09-20T08:08:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=16424"},"modified":"2024-10-13T16:44:14","modified_gmt":"2024-10-13T14:44:14","slug":"musee-correr-e-biblioteca-marciana-venezia-2024","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/09\/20\/musee-correr-e-biblioteca-marciana-venezia-2024\/","title":{"rendered":"Musee Correr e Biblioteca Marciana &#8211; Venezia (2024)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Mus\u00e9e Correr se trouve, depuis 1922, dans les b\u00e2timents qui entourent la place Saint-Marc, dans les espaces de l\u2019aile napol\u00e9onienne et d\u2019une partie des nouvelles procuraties. Il illustre la vie et la culture de la R\u00e9publique de Venise au cours des si\u00e8cles de sa grandeur politique et de son ind\u00e9pendance. La pinacoth\u00e8que r\u00e9unit des chefs-d\u2019\u0153uvre de l\u2019art v\u00e9nitien des origines au XVI<sup>e<\/sup> si\u00e8cle. Plus que la collection elle-m\u00eame, c&#8217;est le b\u00e2timent qui est impressionnant : des salles \u00e9normes, d\u00e9cor\u00e9es du sol au plafond, il faut juste fermer les yeux pour voir le faste de l&#8217;\u00e9poque. Nous avons vu la grande salle de la biblioth\u00e8que, mais un peu d\u00e9\u00e7us de ne pas y voir de livres. Je ne suis pas tr\u00e8s s\u00fbre de comment y acc\u00e9der vraiment. Dans la salle, il y avait une exposition intitul\u00e9e &#8220;The Description of the World&#8221; de Brixy, un artiste qui r\u00e9alise de grandes toiles \u00e0 l&#8217;huile avec des outils et ses mains, mais pas de pinceaux. Je n&#8217;ai pas \u00e9t\u00e9 convaincue. Une autre exposition, celle de Francesco Vezzoli, &#8220;Musei delle Lacrime&#8221;, qui customise des tableaux en y ajoutant des bulles, beaucoup de larmes, des \u00e9l\u00e9ments brillants. Des \u0153uvres pas toutes tr\u00e8s subtiles, avec quelques-unes assez dr\u00f4les.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;L\u2019\u00e9difice conserve encore de nombreuses caract\u00e9ristiques de l\u2019\u00e9poque de Bonaparte et de celle des Habsbourg : une architecture, des fresques et un mobilier, n\u00e9oclassiques, qui offrent un t\u00e9moignage important de la culture et des langages d\u2019une \u00e9poque. Il atteste surtout, presqu\u2019en opposition avec l\u2019ancien Palais des Doges, la volont\u00e9 de refonder une nouvelle saison de l\u2019histoire de Venise, embl\u00e9matiquement repr\u00e9sent\u00e9e par ce palais moderne.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Mus\u00e9e Correr se trouve, depuis 1922, dans les b\u00e2timents qui entourent la place Saint-Marc, dans les espaces de l\u2019aile napol\u00e9onienne et d\u2019une partie des nouvelles procuraties. Il illustre la vie et la culture de la R\u00e9publique de Venise au cours des si\u00e8cles de sa grandeur politique et de son ind\u00e9pendance. La pinacoth\u00e8que r\u00e9unit des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16433,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[117],"tags":[67,112,80],"class_list":["post-16424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-exhibitions","tag-creativity","tag-history","tag-travel"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/09\/eugene-zhyvchik-crQBHAJz5PY-unsplash-scaled.jpg?fit=2560%2C1722&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=16424"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16424\/revisions"}],"predecessor-version":[{"id":16510,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16424\/revisions\/16510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/16433"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=16424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=16424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=16424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}