{"id":16887,"date":"2024-11-02T22:31:58","date_gmt":"2024-11-02T21:31:58","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=16887"},"modified":"2024-11-04T22:33:01","modified_gmt":"2024-11-04T21:33:01","slug":"atelier-kintsugi-orinasu-japan-ici-ceramique-studio-2024","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/11\/02\/atelier-kintsugi-orinasu-japan-ici-ceramique-studio-2024\/","title":{"rendered":"Atelier Kintsugi &#8211; Orinasu Japan &#8211; ICI C\u00e9ramique Studio (2024)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le kintsugi est un art japonais qui permet de r\u00e9parer toute c\u00e9ramique cass\u00e9e. Les fissures et les \u00e9br\u00e9chures ne sont pas cach\u00e9es, mais au contraire mises en valeur par de l&#8217;or. Les deux ateliers \u00e9taient anim\u00e9s par une maitre artisane de kintsugi, Ai Shimizu, venue de Kyoto. Le matin, nous avons appris la technique pour r\u00e9parer une \u00e9br\u00e9chure, puis l&#8217;apr\u00e8s-midi, celle pour recoller des morceaux ensemble. Ai Shimizu nous a parl\u00e9 de son village, o\u00f9 l&#8217;on cultive les Urujyu, des arbres \u00e0 r\u00e9sine. Cette r\u00e9sine est essentielle pour le kintsugi. Colle, laque, c\u00e9ramique, elle est pr\u00e9sente dans toutes les \u00e9tapes, qui prennent d&#8217;ailleurs plusieurs jours. Comme notre sang, cette r\u00e9sine d&#8217;Urujyu est le sang de l&#8217;arbre, rendant vivant l&#8217;objet r\u00e9par\u00e9. C&#8217;est une activit\u00e9 tr\u00e8s m\u00e9ditative et un tr\u00e8s bel art.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Le kintsugi incarne la r\u00e9silience, la beaut\u00e9 de l&#8217;imperfection, et le respect pour la long\u00e9vit\u00e9 des objets, montrant que les cicatrices peuvent devenir sources de force et d&#8217;esth\u00e9tique.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le kintsugi est un art japonais qui permet de r\u00e9parer toute c\u00e9ramique cass\u00e9e. Les fissures et les \u00e9br\u00e9chures ne sont pas cach\u00e9es, mais au contraire mises en valeur par de l&#8217;or. Les deux ateliers \u00e9taient anim\u00e9s par une maitre artisane de kintsugi, Ai Shimizu, venue de Kyoto. Le matin, nous avons appris la technique pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16898,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[134],"tags":[118,238,112],"class_list":["post-16887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-courses","tag-beauty","tag-craft","tag-history"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/11\/riho-kitagawa-JuDPjcutors-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=16887"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16887\/revisions"}],"predecessor-version":[{"id":16902,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/16887\/revisions\/16902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/16898"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=16887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=16887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=16887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}