{"id":17261,"date":"2024-12-14T23:42:36","date_gmt":"2024-12-14T22:42:36","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=17261"},"modified":"2024-12-22T15:41:49","modified_gmt":"2024-12-22T14:41:49","slug":"le-joueur-dechecs-david-sala-2017","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/12\/14\/le-joueur-dechecs-david-sala-2017\/","title":{"rendered":"Le joueur d&#8217;\u00e9checs &#8211; David Sala (2017)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bas\u00e9 sur le roman de Stefan Zweig, ce roman graphique raconte l&#8217;histoire du prodige des \u00e9checs Mirko Czentovic et de Mr B., un homme qui a appris les \u00e9checs en captivit\u00e9 chez les nazis pour faire face \u00e0 son isolement. Sur un bateau, M. B. affronte Czentovic dans un match dramatique qui r\u00e9v\u00e8le les cicatrices psychologiques de son pass\u00e9. Une histoire d&#8217;obsession et de r\u00e9silience. Des illustrations et des portraits magnifiquement color\u00e9s qui expriment une gamme infinie d&#8217;\u00e9motions. Un tr\u00e8s bel aspect visuel pour une histoire plut\u00f4t poignante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Je ne faisais rien d&#8217;autre, je ne dormais plus, ou mal. Le d\u00e9sir exasp\u00e9r\u00e9 de gagner, de me vaincre mi-m\u00eame devenait une esp\u00e8ce de fureur. Cette obsession monomaniaque commen\u00e7ait \u00e0 attaquer non seulement mon cerveau, mais tout mon corps. Je maigris, mes tremblements m&#8217;emp\u00eachaient parfois m\u00eame d&#8217;approcher un verre de mes l\u00e8vres. \u00c0 travers un brouillard rouge, j&#8217;entendais parfois cette voix rauque et m\u00e9chante&#8230; \u00c9CHEC !&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"1024\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/PXL_20241215_1138028622.jpg?resize=764%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-17289\" style=\"width:840px;height:auto\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/PXL_20241215_1138028622-scaled.jpg?resize=764%2C1024&amp;ssl=1 764w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/PXL_20241215_1138028622-scaled.jpg?resize=224%2C300&amp;ssl=1 224w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/PXL_20241215_1138028622-scaled.jpg?resize=768%2C1029&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/PXL_20241215_1138028622-scaled.jpg?resize=1146%2C1536&amp;ssl=1 1146w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/PXL_20241215_1138028622-scaled.jpg?resize=1528%2C2048&amp;ssl=1 1528w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/PXL_20241215_1138028622-scaled.jpg?w=1910&amp;ssl=1 1910w\" sizes=\"auto, (max-width: 764px) 100vw, 764px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bas\u00e9 sur le roman de Stefan Zweig, ce roman graphique raconte l&#8217;histoire du prodige des \u00e9checs Mirko Czentovic et de Mr B., un homme qui a appris les \u00e9checs en captivit\u00e9 chez les nazis pour faire face \u00e0 son isolement. Sur un bateau, M. B. affronte Czentovic dans un match dramatique qui r\u00e9v\u00e8le les cicatrices [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17265,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[256],"tags":[205,166,64],"class_list":["post-17261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graphic-2024","tag-challenge","tag-game","tag-madness"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/ahmed-30d4y92NR9U-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/17261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=17261"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/17261\/revisions"}],"predecessor-version":[{"id":17291,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/17261\/revisions\/17291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/17265"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=17261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=17261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=17261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}