{"id":17276,"date":"2024-12-15T09:29:43","date_gmt":"2024-12-15T08:29:43","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=17276"},"modified":"2024-12-22T23:05:54","modified_gmt":"2024-12-22T22:05:54","slug":"bonobo-moussaka-adeline-dieudonne-2018","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2024\/12\/15\/bonobo-moussaka-adeline-dieudonne-2018\/","title":{"rendered":"Bonobo Moussaka &#8211; Adeline Dieudonn\u00e9 (2018)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">C&#8217;est No\u00ebl et la narratrice est chez son cousin avec ses deux enfants et un couple d&#8217;amis. Elle observe le comportement des invit\u00e9s. Le dominant, qui se comporte comme un bonobo, le soumis, comme un chien. Les femmes regardent, se demandant si elles ont choisi le bon homme. La narratrice se perd un instant dans son enfance, une m\u00e8re qui prend toute la place et brise la jeune fille qu&#8217;elle \u00e9tait. C&#8217;est une triste satire des rapports de domination, mais r\u00e9aliste, avec une question finale : qu&#8217;est-ce que j&#8217;offre \u00e0 mes enfants ? C&#8217;est court, mais puissant, avec de beaux paragraphes qui font r\u00e9fl\u00e9chir. Tr\u00e8s touchant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Et tout \u00e0 coup, j\u2019ai envie de leur demander pardon. Parce que je ne suis pas capable de leur offrir mieux que \u00e7a. Parce qu\u2019ils ne le savent pas encore mais ils vont devoir vivre avec des Philippes, des Gabriels, des rottweilers, des labradors, des canap\u00e9s Ch\u00e2teau d\u2019Ax, des pubs Nutella, des joints de culasse d\u00e9fectueux, des Lakshmi Mittal, des quiches mal partag\u00e9es, des Barbie Curvy, des abrutis du FMI, des d\u00e9g\u00e9n\u00e9r\u00e9s de la BCE, des n\u00e9onazis et des enfants noy\u00e9s. Et je ne sais pas quoi faire pour changer \u00e7a. Mais l\u00e0 maintenant, ils ne se doutent de rien, avec leurs cadeaux de No\u00ebl serr\u00e9s entre leurs bras. Je leur promets silencieusement de ne jamais, jamais casser leur petite bo\u00eete \u00e0 musique int\u00e9rieure. Je leur promets aussi de trouver le moyen de leur laisser un avenir un peu moins affreux. Je sais pas encore comment. Mais je vais trouver.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&#8217;est No\u00ebl et la narratrice est chez son cousin avec ses deux enfants et un couple d&#8217;amis. Elle observe le comportement des invit\u00e9s. Le dominant, qui se comporte comme un bonobo, le soumis, comme un chien. Les femmes regardent, se demandant si elles ont choisi le bon homme. La narratrice se perd un instant dans [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17312,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[255],"tags":[111,31,99],"class_list":["post-17276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books-2024","tag-abuse","tag-family","tag-relationships"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2024\/12\/francesco-ungaro-hA7TBL-t5yo-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/17276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=17276"}],"version-history":[{"count":1,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/17276\/revisions"}],"predecessor-version":[{"id":17313,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/17276\/revisions\/17313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/17312"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=17276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=17276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=17276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}