{"id":18246,"date":"2025-03-11T19:13:11","date_gmt":"2025-03-11T18:13:11","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=18246"},"modified":"2025-03-13T19:24:08","modified_gmt":"2025-03-13T18:24:08","slug":"bourrasques-et-accalmies-jean-jacques-sempe-2013","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2025\/03\/11\/bourrasques-et-accalmies-jean-jacques-sempe-2013\/","title":{"rendered":"Bourrasques et accalmies &#8211; Jean-Jacques Semp\u00e9 (2013)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Avec sa d\u00e9rision habituelle, Semp\u00e9 se moque ici de tout un tas de personnes adultes, de la bourgeoisie bien parisienne \u00e0 la jeunesse New Age. Il capture le charme, l&#8217;humour et la m\u00e9lancolie de la vie avec ses coups de crayons d\u00e9licats, pleins de l\u00e9g\u00e8ret\u00e9 et d&#8217;\u00e9l\u00e9gance. Les quelques mots qui accompagnent certains dessins sont juste l\u00e0 pour rehausser l&#8217;image. J&#8217;aime beaucoup son regard, \u00e0 la fois doux et attentif, sur les petites bizarreries de la nature humaine. Cet ouvrage pour adultes est un petit moment d&#8217;humour et de bonheur de la vie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;- Renaud et moi en avions assez de tous ces pr\u00e9noms alambiqu\u00e9s destin\u00e9s, soi-disant, \u00e0 booster la personnalit\u00e9 de l&#8217;enfant (Sol\u00e8ne a appel\u00e9 ses jumeaux C\u00e9sar et Balthazar, Ghislaine a appel\u00e9 sa fille Sixtine). Nous, nous avons opt\u00e9 pour la simplicit\u00e9\u00a0: Paul. Comme Paul C\u00e9zanne, Paul Gauguin, Paul Val\u00e9ry ou Paul McCartney.&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"885\" height=\"1024\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/03\/PXL_20250313_1814275462.jpg?resize=885%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-18294\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/03\/PXL_20250313_1814275462-scaled.jpg?resize=885%2C1024&amp;ssl=1 885w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/03\/PXL_20250313_1814275462-scaled.jpg?resize=259%2C300&amp;ssl=1 259w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/03\/PXL_20250313_1814275462-scaled.jpg?resize=768%2C888&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/03\/PXL_20250313_1814275462-scaled.jpg?resize=1328%2C1536&amp;ssl=1 1328w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/03\/PXL_20250313_1814275462-scaled.jpg?resize=1771%2C2048&amp;ssl=1 1771w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/03\/PXL_20250313_1814275462-scaled.jpg?w=2000&amp;ssl=1 2000w\" sizes=\"auto, (max-width: 885px) 100vw, 885px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Avec sa d\u00e9rision habituelle, Semp\u00e9 se moque ici de tout un tas de personnes adultes, de la bourgeoisie bien parisienne \u00e0 la jeunesse New Age. Il capture le charme, l&#8217;humour et la m\u00e9lancolie de la vie avec ses coups de crayons d\u00e9licats, pleins de l\u00e9g\u00e8ret\u00e9 et d&#8217;\u00e9l\u00e9gance. Les quelques mots qui accompagnent certains dessins sont [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18247,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[270,280,277,276],"tags":[133,47,98],"class_list":["post-18246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books-2025","category-chalenge-abc-2024-2025-prenom","category-challenge-riquiqui-2025","category-challenge-solidaire-2025","tag-derision","tag-humour","tag-life"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/03\/mael-balland-6FIx6oSx30-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/18246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=18246"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/18246\/revisions"}],"predecessor-version":[{"id":18295,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/18246\/revisions\/18295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/18247"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=18246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=18246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=18246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}