{"id":18931,"date":"2025-06-26T14:22:04","date_gmt":"2025-06-26T12:22:04","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=18931"},"modified":"2025-08-05T10:29:00","modified_gmt":"2025-08-05T08:29:00","slug":"comment-financer-un-monde-plus-juste-les-sentinelles-courrier-international-2024","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2025\/06\/26\/comment-financer-un-monde-plus-juste-les-sentinelles-courrier-international-2024\/","title":{"rendered":"Comment financer un monde plus juste\u00a0? &#8211; Les Sentinelles &#8211; Courrier international (2024)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans le contexte de la construction d&#8217;un monde plus durable, cette nouvelle s\u00e9rie explore la question du financement d&#8217;un monde plus juste \u00e0 travers cinq \u00e9pisodes et divers intervenants (chercheurs, artistes, activistes, etc.), avec des exemples au Rwanda, en C\u00f4te d&#8217;Ivoire, au Br\u00e9sil, en \u00c9quateur et en Tha\u00eflande. On y parle de banques de d\u00e9veloppement \u00e0 orientation \u00ab verte \u00bb, de coop\u00e9ratives qui fonctionnent avec un syst\u00e8me de d\u00e9mocratie participative et encouragent les femmes \u00e0 devenir actrices du monde agricole, ou encore de la mani\u00e8re de penser \u00e0 un avenir plus juste sur le plan climatique. Les finances ne sont pas vraiment mon domaine, mais j&#8217;ai trouv\u00e9 qu&#8217;il y avait quelques \u00e9l\u00e9ments assez int\u00e9ressants, notamment le fait que les personnes les plus touch\u00e9es par les changements climatiques ne sont pas n\u00e9cessairement celles qui polluent le plus, et que pour que tous ces projets fonctionnent, les populations doivent pouvoir comprendre les enjeux, ce qui n&#8217;est pas toujours \u00e9vident. Un petit podcast vraiment int\u00e9ressant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Ce qui est un peu particulier sur ce d\u00e9bat, des financements verts et du changement climatique, peut-\u00eatre que c&#8217;est pour \u00e7a que c&#8217;est aussi difficile \u00e0 faire avancer, c&#8217;est qu&#8217;en fait, c&#8217;est une des rares fois qu&#8217;on a vraiment un d\u00e9fi qui affecte tout le monde en m\u00eame temps. Je pense que souvent les gens pensent au d\u00e9veloppement, ils pensent au pays du tiers-monde, c&#8217;est une partie de la mappemonde, c&#8217;est pas tout le monde, et je pense que la pand\u00e9mie du corona et ce probl\u00e8me du changement climatique, nous montre qu&#8217;en fait y&#8217;a pas le tiers-monde et l&#8217;autre monde. On est tous dans le m\u00eame monde. Et donc, si on fait pas quelque chose pour qu&#8217;il y ait des changements rapides, on va tous \u00eatre affect\u00e9 de la m\u00eame fa\u00e7on&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-colibri-color-4-color\">Cinq \u00e9pisodes d&#8217;environ 10 minutes<\/mark><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\">\u00c9pisode 1. Diana C\u00e1rdenas Monar\u00a0: \u201cLa finance mondiale ne r\u00e9pond pas au d\u00e9fi climatique\u201d<br>\u00c9pisode 2. Kampeta Pitchette Sayinzoga, au Rwanda\u00a0: \u201cNous avons tous besoin de financements en m\u00eame temps\u201d<br>\u00c9pisode 3. Assata Doumbia, en C\u00f4te d\u2019Ivoire\u00a0: \u201cNous permettons aux femmes d\u2019avoir leurs propres revenus\u201d<br>\u00c9pisode 4. Emilie Pradichit, en Tha\u00eflande\u00a0: \u201cIl faut changer les relations avec les grands bailleurs de fonds\u201d<br>\u00c9pisode 5. Sebasti\u00e3o Salgado, au Br\u00e9sil\u00a0: \u201cQuel est le co\u00fbt des arbres que l\u2019on doit replanter\u00a0?\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le contexte de la construction d&#8217;un monde plus durable, cette nouvelle s\u00e9rie explore la question du financement d&#8217;un monde plus juste \u00e0 travers cinq \u00e9pisodes et divers intervenants (chercheurs, artistes, activistes, etc.), avec des exemples au Rwanda, en C\u00f4te d&#8217;Ivoire, au Br\u00e9sil, en \u00c9quateur et en Tha\u00eflande. On y parle de banques de d\u00e9veloppement [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18998,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[76],"tags":[128,74,143],"class_list":["post-18931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcasts","tag-entitlement","tag-environment","tag-money"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2025\/06\/joshua-hoehne-p_Ye2kA2F0A-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/18931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=18931"}],"version-history":[{"count":5,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/18931\/revisions"}],"predecessor-version":[{"id":19122,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/18931\/revisions\/19122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/18998"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=18931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=18931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=18931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}