{"id":21622,"date":"2026-05-14T14:33:26","date_gmt":"2026-05-14T12:33:26","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=21622"},"modified":"2026-05-14T14:33:26","modified_gmt":"2026-05-14T12:33:26","slug":"la-revolte-des-cigarieres-eric-burnand-fanny-vaucher-2026","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2026\/05\/14\/la-revolte-des-cigarieres-eric-burnand-fanny-vaucher-2026\/","title":{"rendered":"La r\u00e9volte des cigari\u00e8res &#8211; Eric Burnand &amp; Fanny Vaucher (2026)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ce roman graphique retrace le combat des cigari\u00e8res de l\u2019entreprise Vaucher \u00e0 Yverdon-les-Bains en 1907. Confront\u00e9es \u00e0 des salaires d\u00e9risoires, \u00e0 un syst\u00e8me d\u2019amendes abusif ainsi qu\u2019\u00e0 des conditions de travail p\u00e9nibles et dangereuses pour leur sant\u00e9, ces ouvri\u00e8res ont choisi de se mettre en gr\u00e8ve avec une force et une d\u00e9termination remarquables, malgr\u00e9 la pr\u00e9carit\u00e9 dans laquelle elles vivaient d\u00e9j\u00e0. Cette lutte collective constitue un \u00e9pisode passionnant de l\u2019histoire sociale suisse et rappelle combien les droits des travailleurs ont \u00e9t\u00e9 obtenus au prix de nombreux sacrifices. Une lecture \u00e0 la fois instructive et profond\u00e9ment inspirante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Ouvri\u00e8res de tous les m\u00e9tiers, brisez avec l&#8217;indiff\u00e9rence coupable, ne vous reposez pas sur la charit\u00e9 publique. Celle qui est assist\u00e9e est encore plus esclave que les autres. <br>Venez au syndicat, vous n&#8217;avez pas du sang de jaunes dans les veines, ni de tra\u00eetres, ni d&#8217;esclaves, ni de poltronnes; vous avez des besoins de femmes libres, vous avez besoin d&#8217;ind\u00e9pendance, de bien-\u00eatre, de loisirs. Pour obtenir tout cela, ne comptez ni sur la charit\u00e9, ni sur les patrons, ni sur les hommes, ni m\u00eame sur le ciel, ne comptez que sur vous-m\u00eames et agissez\u00a0!&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"1024\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2026\/05\/IMG_1658.jpeg?resize=675%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-21639\" style=\"width:840px;height:auto\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2026\/05\/IMG_1658-scaled.jpeg?resize=675%2C1024&amp;ssl=1 675w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2026\/05\/IMG_1658-scaled.jpeg?resize=198%2C300&amp;ssl=1 198w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2026\/05\/IMG_1658-scaled.jpeg?resize=768%2C1166&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2026\/05\/IMG_1658-scaled.jpeg?resize=1012%2C1536&amp;ssl=1 1012w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2026\/05\/IMG_1658-scaled.jpeg?resize=1349%2C2048&amp;ssl=1 1349w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2026\/05\/IMG_1658-scaled.jpeg?w=1687&amp;ssl=1 1687w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ce roman graphique retrace le combat des cigari\u00e8res de l\u2019entreprise Vaucher \u00e0 Yverdon-les-Bains en 1907. Confront\u00e9es \u00e0 des salaires d\u00e9risoires, \u00e0 un syst\u00e8me d\u2019amendes abusif ainsi qu\u2019\u00e0 des conditions de travail p\u00e9nibles et dangereuses pour leur sant\u00e9, ces ouvri\u00e8res ont choisi de se mettre en gr\u00e8ve avec une force et une d\u00e9termination remarquables, malgr\u00e9 la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21623,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[290],"tags":[111,112,32],"class_list":["post-21622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graphic-stories-2026","tag-abuse","tag-history","tag-women"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2026\/05\/alexandre-trouve-wyAMbXYLzI4-unsplash-scaled.jpg?fit=1707%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/21622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=21622"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/21622\/revisions"}],"predecessor-version":[{"id":21640,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/21622\/revisions\/21640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/21623"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=21622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=21622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=21622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}