{"id":3307,"date":"2021-03-24T17:51:25","date_gmt":"2021-03-24T16:51:25","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=3307"},"modified":"2021-04-02T17:51:44","modified_gmt":"2021-04-02T15:51:44","slug":"therapie-de-groupe-pour-marionnettes-confinees-theatre-des-marionnettes-de-geneve-2021","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/03\/24\/therapie-de-groupe-pour-marionnettes-confinees-theatre-des-marionnettes-de-geneve-2021\/","title":{"rendered":"Th\u00e9rapie de groupe pour marionnettes confin\u00e9es &#8211; Th\u00e9\u00e2tre des Marionnettes de Gen\u00e8ve (2021)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un mini, <a href=\"https:\/\/www.marionnettes.ch\/\" data-type=\"URL\" data-id=\"https:\/\/www.marionnettes.ch\/\">mini-m\u00e9trage<\/a> du Th\u00e9\u00e2tre des Marionnettes de Gen\u00e8ve. Les pauvres marionnettes, au ch\u00f4mage depuis des mois, d\u00e9priment. Le th\u00e9\u00e2tre leur offre ici la possibilit\u00e9 de faire une th\u00e9rapie de groupe, \u00e0 la &#8220;Alcooliques anonymes&#8221;. Chacun se pr\u00e9sente et t\u00e9moigne de sa souffrance, de ses croyances. Un animateur bien intentionn\u00e9 essaie de garder un peu d&#8217;ordre dans ce groupe qui part facilement en chansons. C&#8217;est tr\u00e8s mignon et une belle fa\u00e7on de faire entendre la voix des marionnettistes derri\u00e8re celle de leurs marionnettes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Regardez autour de vous ! Regardez bien ! On est tous manipul\u00e9s&#8221;&#8230; (et les marionnettes se retournent pour regarder leur marionnettiste).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un mini, mini-m\u00e9trage du Th\u00e9\u00e2tre des Marionnettes de Gen\u00e8ve. Les pauvres marionnettes, au ch\u00f4mage depuis des mois, d\u00e9priment. Le th\u00e9\u00e2tre leur offre ici la possibilit\u00e9 de faire une th\u00e9rapie de groupe, \u00e0 la &#8220;Alcooliques anonymes&#8221;. Chacun se pr\u00e9sente et t\u00e9moigne de sa souffrance, de ses croyances. Un animateur bien intentionn\u00e9 essaie de garder un peu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3376,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[92,44,39],"class_list":["post-3307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bits-bobs","tag-hope","tag-hopelessness","tag-virus"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/03\/anda-deea-5ZFqXzcmZa0-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/3307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=3307"}],"version-history":[{"count":2,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/3307\/revisions"}],"predecessor-version":[{"id":3311,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/3307\/revisions\/3311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/3376"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=3307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=3307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=3307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}