{"id":5281,"date":"2021-06-05T22:27:00","date_gmt":"2021-06-05T20:27:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=5281"},"modified":"2021-06-12T14:25:10","modified_gmt":"2021-06-12T12:25:10","slug":"la-chute-de-lempire-americain-denys-arcand-2018","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/06\/05\/la-chute-de-lempire-americain-denys-arcand-2018\/","title":{"rendered":"La chute de l&#8217;empire am\u00e9ricain &#8211; Denys Arcand (2018)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pierre-Paul poss\u00e8de un doctorat en philosophie mais travaille comme livreur. T\u00e9moin d&#8217;un hold-up rat\u00e9, il se retrouve avec, \u00e0 ses pieds, deux \u00e9normes sacs remplis de billets de banque, qu&#8217;il embarque sans trop y penser. Il sera oblig\u00e9 de s&#8217;ajoindre un ex-taulard qui a fait du droit en prison, une escort-girl dont il tombera amoureux et un sp\u00e9cialiste de l&#8217;\u00e9vasion fiscale pour r\u00e9ussir \u00e0 faire dispara\u00eetre cet argent. L&#8217;argent servira \u00e0 cr\u00e9er une fondation qui vient en aide aux d\u00e9munis. Troisi\u00e8me film de la trilogie de Denys Arcand, apr\u00e8s le D\u00e9clin de l&#8217;empire am\u00e9ricain et les Invasions barbares, je peine un peu \u00e0 voir le lien direct, hormis une critique large de la soci\u00e9t\u00e9. Int\u00e9ressantes r\u00e9flexions sur l&#8217;honn\u00eatet\u00e9, l&#8217;intelligence, le pouvoir de l&#8217;argent, port\u00e9 par des tirades magnifiques. Un joli film.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;- Ben si t&#8217;es si intelligent que \u00e7a, pourquoi t&#8217;es pas pr\u00e9sident d&#8217;une banque, recteur de l&#8217;universit\u00e9. Celui de Lennoxville   est parti avec une indemnit\u00e9 de 150&#8217;000. <br>&#8211; C&#8217;est ce que je te dis. Je suis trop intelligent.<br>&#8211; Pardon !<br>&#8211; L&#8217;intelligence, c&#8217;est pas un avantage, c&#8217;est un handicap&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pierre-Paul poss\u00e8de un doctorat en philosophie mais travaille comme livreur. T\u00e9moin d&#8217;un hold-up rat\u00e9, il se retrouve avec, \u00e0 ses pieds, deux \u00e9normes sacs remplis de billets de banque, qu&#8217;il embarque sans trop y penser. Il sera oblig\u00e9 de s&#8217;ajoindre un ex-taulard qui a fait du droit en prison, une escort-girl dont il tombera amoureux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5284,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[59,36,47],"class_list":["post-5281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films-2021","tag-crime","tag-friendship","tag-humour"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/jason-leung-SAYzxuS1O3M-unsplash-scaled.jpg?fit=2560%2C1706&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=5281"}],"version-history":[{"count":2,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5281\/revisions"}],"predecessor-version":[{"id":5286,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5281\/revisions\/5286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/5284"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=5281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=5281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=5281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}