{"id":5292,"date":"2021-06-04T14:26:00","date_gmt":"2021-06-04T12:26:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=5292"},"modified":"2022-07-17T14:34:28","modified_gmt":"2022-07-17T12:34:28","slug":"le-chat-du-rabbin-tome-8-petit-panier-aux-amandes-joann-sfar-2018","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/06\/04\/le-chat-du-rabbin-tome-8-petit-panier-aux-amandes-joann-sfar-2018\/","title":{"rendered":"Le Chat du Rabbin \u2013 Tome 8.  Petit panier aux amandes \u2013 Joann Sfar (2018)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lui est juif, elle est catholique. Elle aimerait se convertir pour lui faire plaisir. Le rabbin, mari de Zblaya, refuse. L&#8217;amour n&#8217;est pas une bonne raison pour adh\u00e9rer \u00e0 une religion qui est d\u00e9crite ici comme tellement complexe, contraignante, pleine de contradictions. C&#8217;est aussi l&#8217;occasion de parler de tentation, d&#8217;infid\u00e9lit\u00e9, de la place de la femme, compagne ou m\u00e8re, dans la vie des hommes. Une bande dessin\u00e9e qui initie de belles r\u00e9flexions sur le juda\u00efsme, questions qui finalement s&#8217;appliquent \u00e0 toute religion. Et j&#8217;aime toujours autant ce chat impertinent et provocateur, limite cruel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Non, non, tu te trompes. Tu n&#8217;as pas compris. Tous ces rituels qu&#8217;ils accomplissent en permanence&nbsp;: se laver les mains, faire une pri\u00e8re avant de manger&#8230; avant de dormir, avant de passer une porte, avant de boire un verre d&#8217;eau, avant de cuire du pain, d&#8217;enterrer un proche, de serrer la main \u00e0 un copain, tous ces trucs, trucs, trucs partout. \u00c7a sert \u00e0 pas penser. \u00c0 la mort.&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1858\" height=\"1489\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/IMG-20220627-WA00043.jpg?resize=1858%2C1489&#038;ssl=1\" alt=\"\" class=\"wp-image-10070\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/IMG-20220627-WA00043.jpg?w=1858&amp;ssl=1 1858w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/IMG-20220627-WA00043.jpg?resize=300%2C240&amp;ssl=1 300w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/IMG-20220627-WA00043.jpg?resize=1024%2C821&amp;ssl=1 1024w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/IMG-20220627-WA00043.jpg?resize=768%2C615&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/IMG-20220627-WA00043.jpg?resize=1536%2C1231&amp;ssl=1 1536w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Lui est juif, elle est catholique. Elle aimerait se convertir pour lui faire plaisir. Le rabbin, mari de Zblaya, refuse. L&#8217;amour n&#8217;est pas une bonne raison pour adh\u00e9rer \u00e0 une religion qui est d\u00e9crite ici comme tellement complexe, contraignante, pleine de contradictions. C&#8217;est aussi l&#8217;occasion de parler de tentation, d&#8217;infid\u00e9lit\u00e9, de la place de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[103],"tags":[127,85,107],"class_list":["post-5292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graphic-2021","tag-hypocrisy","tag-infidelity","tag-religion"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/lucas-mendes-DutIW-MX7vM-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=5292"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5292\/revisions"}],"predecessor-version":[{"id":10071,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5292\/revisions\/10071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/5293"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=5292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=5292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=5292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}