{"id":5585,"date":"2021-07-17T23:49:00","date_gmt":"2021-07-17T21:49:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=5585"},"modified":"2021-07-18T19:19:20","modified_gmt":"2021-07-18T17:19:20","slug":"amarula-adeline-dieudonne-2018","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/07\/17\/amarula-adeline-dieudonne-2018\/","title":{"rendered":"Amarula &#8211; Adeline Dieudonn\u00e9 (2018)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Juliette a 28 ans et est vendeuse de sextoy \u00e0 domicile lors de soir\u00e9e Upperware. Andr\u00e9 a 96 ans et est son voisin. Ils se retrouvent de temps en temps autour d&#8217;un verre d&#8217;Amarula. Andr\u00e9 a perdu sa femme, son \u00e2me s\u0153ur affective et sexuelle, il y a 29 ans. Un soir, il demande \u00e0 Juliette de lui montrer sa valise d&#8217;accessoires. Elle les sort un \u00e0 un&#8230; Cool\u2019\u00d4, Orgasmik, le plumeau synth\u00e9tique, les menottes en fourrure, puis le Rabbit, elle lui explique, fous rires, et finalement le Poney-Tail, explications \u00e0 nouveau et fous rires encore plus intenses. Joie pour le vieil homme de se rendre compte qu&#8217;il vit, il pense \u00e0 sa femme&#8230; Puis Juliette entend son c\u0153ur s&#8217;arr\u00eater. Toute petite nouvelle, mais tellement jolie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Elle pense \u00e0 toutes les mains qui l\u2019ont touch\u00e9e, elle. Son joli corps de danseuse. Il y en a eu beaucoup. Des f\u00e9briles, des timides, des avides, des souples, des rassurantes, des pingres, des gourmandes, des m\u00e9caniques, des aveugles. Et d\u2019autres, trop rares, qui l\u2019ont \u00e9cout\u00e9e. Des curieuses, des attentives, des g\u00e9n\u00e9reuses comme un air d\u2019op\u00e9ra. Celles qu\u2019elle n\u2019oubliera pas, imprim\u00e9es dans sa chair, enchev\u00eatr\u00e9es dans son ADN.&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juliette a 28 ans et est vendeuse de sextoy \u00e0 domicile lors de soir\u00e9e Upperware. Andr\u00e9 a 96 ans et est son voisin. Ils se retrouvent de temps en temps autour d&#8217;un verre d&#8217;Amarula. Andr\u00e9 a perdu sa femme, son \u00e2me s\u0153ur affective et sexuelle, il y a 29 ans. Un soir, il demande \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5590,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[81],"tags":[131,19,21],"class_list":["post-5585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-short-stories","tag-elderly","tag-love","tag-sex"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/07\/gauravdeep-singh-bansal-caC13DIDe9E-unsplash-1-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=5585"}],"version-history":[{"count":2,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5585\/revisions"}],"predecessor-version":[{"id":5588,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/5585\/revisions\/5588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/5590"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=5585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=5585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=5585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}