{"id":6151,"date":"2021-06-01T07:35:00","date_gmt":"2021-06-01T05:35:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=6151"},"modified":"2021-09-29T10:16:53","modified_gmt":"2021-09-29T08:16:53","slug":"fables-animalieres-les-oiseaux-les-betes-sauvages-et-les-fils-dadam-nuits-146-a-152","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/06\/01\/fables-animalieres-les-oiseaux-les-betes-sauvages-et-les-fils-dadam-nuits-146-a-152\/","title":{"rendered":"Fables animali\u00e8res, les Oiseaux, Les B\u00eates sauvages et les Fils d&#8217;Adam &#8211; Nuits 146 \u00e0 152"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Des fables animali\u00e8res arabes. Comme les fables d&#8217;Esope ou celles de La Fontaine, des animaux qui mettent en exergue des d\u00e9fauts et des qualit\u00e9s propres aux \u00eatres humains. On y retrouve la sempiternelle relation entre le renard rus\u00e9 et le loup un peu simplet, une histoire de renard et de corbeau, mais o\u00f9 le corbeau est plus fut\u00e9 que le renard ou encore une complicit\u00e9 entre une puce et une souris pour duper un riche n\u00e9gociant. C&#8217;est bien moralisateur et assez diff\u00e9rent des contes pr\u00e9c\u00e9dents.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><em>&#8220;J&#8217;aimerais tant retrouver un jour cet \u00eatre cher<\/em><br><em>Et pour lui ne rien taire des ravages de l&#8217;absence.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des fables animali\u00e8res arabes. Comme les fables d&#8217;Esope ou celles de La Fontaine, des animaux qui mettent en exergue des d\u00e9fauts et des qualit\u00e9s propres aux \u00eatres humains. On y retrouve la sempiternelle relation entre le renard rus\u00e9 et le loup un peu simplet, une histoire de renard et de corbeau, mais o\u00f9 le corbeau [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[78,36,28],"class_list":["post-6151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-mille-et-une-nuits","tag-dependency","tag-friendship","tag-nature"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/06\/erik-karits-E78eA9uupLU-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/6151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=6151"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/6151\/revisions"}],"predecessor-version":[{"id":6605,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/6151\/revisions\/6605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/6603"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=6151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=6151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=6151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}