{"id":6223,"date":"2021-08-15T22:18:00","date_gmt":"2021-08-15T20:18:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=6223"},"modified":"2021-09-05T21:09:14","modified_gmt":"2021-09-05T19:09:14","slug":"le-dernier-bain-de-gustave-flaubert-regis-jauffret-2021","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/08\/15\/le-dernier-bain-de-gustave-flaubert-regis-jauffret-2021\/","title":{"rendered":"Le dernier bain de Gustave Flaubert &#8211; R\u00e9gis Jauffret (2021)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gustave Flaubert prend son dernier bain et ce faisant revoit sa vie enti\u00e8re. Il raconte sa jeunesse, ses amours, ses romans. Il mentionne largement sa correspondance avec ses ma\u00eetresses et amants, correspondance qu&#8217;il serait int\u00e9ressant de lire si ce n&#8217;est qu&#8217;elle repr\u00e9sente cinq volumes et un index dans la collection La Pl\u00e9iade. Dans son bain, ses personnages viennent lui rendre visite, Bouvard et P\u00e9cuchet en souci que leur histoire ne soit pas termin\u00e9e et Emma Bovary qui lui reproche de ne m\u00eame pas avoir r\u00e9ussi \u00e0 d\u00e9cider de la couleur de ses yeux et de lui avoir affubl\u00e9 une fine moustache noire sur la l\u00e8vre sup\u00e9rieure. M\u00e9lange de roman et de biographie, un vrai plaisir d&#8217;entrer dans ces moments de la vie de Flaubert, tout \u00e7a avec un fond d&#8217;humour et de d\u00e9rision. Ce livre est accompagn\u00e9 d&#8217;un &#8220;chutier&#8221;, passages retir\u00e9s du manuscrit. Quelque chose que je n&#8217;avais jamais vu auparavant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Il allait cuisiner savamment. Une cuill\u00e8re \u00e0 caf\u00e9 d&#8217;encre noire convenablement repartie lui suffirait. Il avait pass\u00e9 l&#8217;\u00e2ge d&#8217;\u00eatre marmiton. Il n&#8217;\u00e9tait pas du genre \u00e0 rater une sauce d&#8217;adjectifs ni \u00e0 br\u00fbler un r\u00f4ti d&#8217;adverbes. Il en avait fricass\u00e9 des po\u00eal\u00e9es de vocabulaire.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gustave Flaubert prend son dernier bain et ce faisant revoit sa vie enti\u00e8re. Il raconte sa jeunesse, ses amours, ses romans. Il mentionne largement sa correspondance avec ses ma\u00eetresses et amants, correspondance qu&#8217;il serait int\u00e9ressant de lire si ce n&#8217;est qu&#8217;elle repr\u00e9sente cinq volumes et un index dans la collection La Pl\u00e9iade. Dans son bain, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6224,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[94,124,48],"class_list":["post-6223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-book","tag-literature","tag-loss","tag-weirdness"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/08\/florian-rieder-PPG_TCVlwHI-unsplash-scaled-e1630704991181.jpg?fit=1707%2C1472&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/6223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=6223"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/6223\/revisions"}],"predecessor-version":[{"id":6294,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/6223\/revisions\/6294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/6224"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=6223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=6223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=6223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}