{"id":7732,"date":"2021-11-22T16:13:00","date_gmt":"2021-11-22T15:13:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=7732"},"modified":"2021-11-26T16:26:36","modified_gmt":"2021-11-26T15:26:36","slug":"ikonikat-1000-manieres-de-regarder-une-oeuvre-fondation-orange-2021","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/11\/22\/ikonikat-1000-manieres-de-regarder-une-oeuvre-fondation-orange-2021\/","title":{"rendered":"Ikonikat &#8211; 1000 mani\u00e8res de regarder une \u0153uvre &#8211; Fondation Orange (2021)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ikonikat est une innovation d\u00e9velopp\u00e9e par le CNRS pour permettre de mieux comprendre ce qui nous attire dans un tableau, comment chemine notre regard dans une \u0153uvre. Ce mini-MOOC nous demande de regarder six tableaux tr\u00e8s diff\u00e9rents, Vermeer, Pissarro, Delaunay et d&#8217;entourer ce que nous voyons dans l&#8217;ordre dans lequel les \u00e9l\u00e9ments ont attir\u00e9 notre regard. Ludique comme petite activit\u00e9, o\u00f9 vont mes yeux d&#8217;abord et ensuite. Int\u00e9ressant de voir aussi apr\u00e8s ce qui a attir\u00e9 les regards des autres personnes qui ont particip\u00e9 \u00e0 l&#8217;activit\u00e9. Apr\u00e8s quelques mois de fonctionnement, un webinaire devrait nous pr\u00e9senter les conclusions de ce petit test.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Peinte vers 1660 par Johannes Vermeer,&nbsp;La Laiti\u00e8re&nbsp;appartient de nos jours \u00e0 la collection du Rijksmuseum d\u2019Amsterdam. La saillance des \u00e9l\u00e9ments picturaux est particuli\u00e8rement soutenue par le contraste des couleurs chaudes et froides&#8230; &#8230; mais \u00e9galement par la ma\u00eetrise de la lumi\u00e8re qui donne \u00e0 ce tableau une intensit\u00e9 particuli\u00e8re. Si le bleu des v\u00eatements a attir\u00e9 votre regard, il s\u2019av\u00e8re que pour de diminuer le co\u00fbt des mat\u00e9riaux, Vermeer a utilis\u00e9 un pigment de synth\u00e8se \u00e0 base de cobalt, le smalt, avant d\u2019appliquer le bleu outremer pour peindre le tablier.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ikonikat est une innovation d\u00e9velopp\u00e9e par le CNRS pour permettre de mieux comprendre ce qui nous attire dans un tableau, comment chemine notre regard dans une \u0153uvre. Ce mini-MOOC nous demande de regarder six tableaux tr\u00e8s diff\u00e9rents, Vermeer, Pissarro, Delaunay et d&#8217;entourer ce que nous voyons dans l&#8217;ordre dans lequel les \u00e9l\u00e9ments ont attir\u00e9 notre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7731,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[134],"tags":[118,67,25],"class_list":["post-7732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-courses","tag-beauty","tag-creativity","tag-learning"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/11\/daniela-diaz-U0lQNabx2hE-unsplash-scaled-e1637940366415.jpg?fit=1696%2C1386&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=7732"}],"version-history":[{"count":4,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7732\/revisions"}],"predecessor-version":[{"id":7757,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7732\/revisions\/7757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/7731"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=7732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=7732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=7732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}