{"id":7917,"date":"2021-12-15T13:27:00","date_gmt":"2021-12-15T12:27:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=7917"},"modified":"2026-01-18T18:10:22","modified_gmt":"2026-01-18T17:10:22","slug":"les-pecheurs-de-perles-georges-bizet-1863","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/12\/15\/les-pecheurs-de-perles-georges-bizet-1863\/","title":{"rendered":"Les p\u00eacheurs de perles &#8211; Georges Bizet (1863)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Comme tous ces op\u00e9ras, l&#8217;intrigue est assez \u00e9l\u00e9mentaire. L&#8217;histoire se passe \u00e0 Ceylan dans un village de p\u00eacheurs. Zurga, \u00e9lu chef, et Nadir sont amis. Ils se souviennent de Le\u00efla dont ils \u00e9taient tous deux amoureux, mais avaient promis de renoncer \u00e0 cet amour pour pr\u00e9server leur amiti\u00e9. Forc\u00e9ment, \u00e7a ne se passe pas comme \u00e7a. Nadir et Le\u00efla se retrouvent, sont surpris par le pr\u00eatre Nourabad et condamn\u00e9s au b\u00fbcher par Zurga, jaloux&#8230; qui finalement les laissera s&#8217;\u00e9vader. Dans cette version mise en sc\u00e8ne par la N\u00e9erlandaise Lotte de Beer, toute l&#8217;histoire a \u00e9t\u00e9 int\u00e9gr\u00e9e dans un jeu de t\u00e9l\u00e9-r\u00e9alit\u00e9 style Koh Lanta, o\u00f9 le public peut voter pour les trois protagonistes. Il y a m\u00eame un micro-trottoir o\u00f9 des gens dans la rue sont interrog\u00e9s pour savoir s&#8217;il faut tuer les amants ou pas. \u00c7a matche \u00e9tonnamment bien avec le livret de cet op\u00e9ra. Les d\u00e9cors sont sublimes avec un gigantesque disque \u00e0 l&#8217;arri\u00e8re de la sc\u00e8ne qui sert tant\u00f4t d&#8217;\u00e9cran de t\u00e9l\u00e9vision, tant\u00f4t d&#8217;immeuble o\u00f9 l&#8217;on voit des gens suivre l&#8217;\u00e9mission ou encore de lune gigantesque. C&#8217;est tr\u00e8s dense \u00e0 regarder, il se passe beaucoup de choses sur sc\u00e8ne, mais c&#8217;est magnifique. Une merveilleuse soir\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Le\u00efla : Zurga, je viens demander gr\u00e2ce. Par Brahma, par le ciel, par tes mains que j&#8217;embrasse, \u00c9pargne un innocent et ne frappe que moi ! Pour moi je ne crains rien, Zurga, Mais je tremble pour lui ! Ah ! Sois sensible \u00e0 ma plainte Et deviens notre appui. Il me donne son \u00e2me ! Il est tout mon amour !<br><em>Zurga<\/em> : Tout son amour !<br><em>Le\u00efla <\/em> : Ardente flamme, h\u00e9las ! Voici son dernier jour\u202f!<br><em>Zurga<\/em> : Son dernier jour !<br><em>Le\u00efla <\/em> : Ah ! Piti\u00e9 Zurga, ah, piti\u00e9 ! Par ma voix qui supplie, Ah, laisse-toi fl\u00e9chir ! Accorde-moi sa vie, Zurga je t&#8217;en conjure, Accorde-moi sa vie, Pour m&#8217;aider \u00e0 mourir !<br><em>Zurga<\/em> : Qu&#8217;entends-je ?<br><em>Le\u00efla <\/em> : Ah, laisse-toi fl\u00e9chir ! Accorde-moi sa vie, Pour m&#8217;aider \u00e0 mourir !<br><em>Zurga<\/em> : Pour t&#8217;aider \u00e0 mourir ! Ah\u202f! Nadir ! J&#8217;aurais pu lui pardonner peut-\u00eatre Et le sauver, car nous \u00e9tions amis\u202f! Mais tu l&#8217;aimes\u202f!<br><em>Le\u00efla <\/em> : Grand Dieu !<br><em>Zurga<\/em> : Tu l&#8217;aimes !<br><em>Le\u00efla <\/em> : Je fr\u00e9mis !<br><em>Zurga<\/em> : Tu l&#8217;aimes ! Ce mot seul a ranim\u00e9 ma haine et ma fureur !<br><em>Le\u00efla <\/em> : Dieu\u202f!<br><em>Zurga<\/em> : En croyant le sauver, Tu le perds pour jamais\u202f!<br><em>Le\u00efla <\/em> : Par gr\u00e2ce, par piti\u00e9\u202f!<br><em>Zurga<\/em> : Plus de pri\u00e8re vaine\u202f!<br><em>Le\u00efla <\/em> : Par gr\u00e2ce, par piti\u00e9\u202f!<br><em>Zurga<\/em> : Je suis jaloux\u202f!<br><em>Le\u00efla <\/em> : Jaloux\u202f?<br><em>Zurga<\/em> : Comme lui, Le\u00efla, je t&#8217;aimais\u202f!<br><em>Le\u00efla <\/em> : Ah\u202f! De mon amour pour lui Tu m&#8217;oses faire un crime ?<br><em>Zurga<\/em> : Son crime est d&#8217;\u00eatre aim\u00e9 Quand je ne le suis pas\u202f!&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-colibri-color-4-color\">Cr\u00e9\u00e9 \u00e0 Paris en 1863<br>Derni\u00e8re fois au Grand Th\u00e9\u00e2tre de Gen\u00e8ve en 1950<\/mark><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme tous ces op\u00e9ras, l&#8217;intrigue est assez \u00e9l\u00e9mentaire. L&#8217;histoire se passe \u00e0 Ceylan dans un village de p\u00eacheurs. Zurga, \u00e9lu chef, et Nadir sont amis. Ils se souviennent de Le\u00efla dont ils \u00e9taient tous deux amoureux, mais avaient promis de renoncer \u00e0 cet amour pour pr\u00e9server leur amiti\u00e9. Forc\u00e9ment, \u00e7a ne se passe pas comme [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7916,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[86,69,19],"class_list":["post-7917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-operas","tag-betrayal","tag-courage","tag-love"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/susan-wilkinson-jaUiFAjlGXE-unsplash-scaled.jpg?fit=1920%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=7917"}],"version-history":[{"count":2,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7917\/revisions"}],"predecessor-version":[{"id":20049,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7917\/revisions\/20049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/7916"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=7917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=7917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=7917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}