{"id":7933,"date":"2021-12-20T22:45:00","date_gmt":"2021-12-20T21:45:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=7933"},"modified":"2022-01-01T18:47:16","modified_gmt":"2022-01-01T17:47:16","slug":"robinsons-pere-et-fils-tronchet-2019","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/12\/20\/robinsons-pere-et-fils-tronchet-2019\/","title":{"rendered":"Robinsons, p\u00e8re et fils &#8211; Tronchet (2019)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Didier Tronchet quitte l&#8217;Occident pour l&#8217;\u00eele aux Nattes, Oc\u00e9an Indien, avec son fils de 13 ans. Quitter la civilisation, retourner au vrai, vivre. Deux \u00e9v\u00e9nements inattendus. L&#8217;auteur pensait renforcer le lien avec son fils, le prot\u00e9ger, le cajoler, mais celui-ci s&#8217;adapte \u00e0 l&#8217;ile et \u00e0 sa nouvelle vie une aisance qui \u00e9tonne le p\u00e8re. Et l&#8217;\u00eele r\u00e9v\u00e8le aussi que lorsque la vie est tranquille \u00e0 ext\u00e9rieur, c&#8217;est l&#8217;int\u00e9rieur qui commence \u00e0 \u00eatre mouvement\u00e9 et qu&#8217;il faut s&#8217;en occuper. Tr\u00e8s jolie bande dessin\u00e9e, tr\u00e8s touchante.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;- Mon cerveau d&#8217;occidental est assez encombrant&#8230; Depuis que je suis ici je dialogue beaucoup avec lui&#8230; \u00c7a ne me rassure pas sur ma sant\u00e9 mentale&#8230; J&#8217;aime bien me repr\u00e9senter mon cerceau comme une entit\u00e9 autonome sur pattes. \u00c7a m&#8217;aide \u00e0 me comprendre.<br>&#8211; Ah ben ouais mais c&#8217;est hyper moche. <\/em><br><em>&#8211; Mon cerveau aime bien tout ma\u00eetriser&#8230; Mettre les exp\u00e9riences dans des boites avec des \u00e9tiquettes dessus.<br>&#8211; Normal, non ?<br>&#8211; Des r\u00e9f\u00e9rences rassurantes et connues&#8230;<br>&#8211; Ben, oui&#8230;&#8221;<\/em><\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/20220101_1540552.jpg?resize=414%2C512&#038;ssl=1\" alt=\"\" class=\"wp-image-8098\" width=\"414\" height=\"512\" srcset=\"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/20220101_1540552-scaled.jpg?resize=828%2C1024&amp;ssl=1 828w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/20220101_1540552-scaled.jpg?resize=243%2C300&amp;ssl=1 243w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/20220101_1540552-scaled.jpg?resize=768%2C950&amp;ssl=1 768w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/20220101_1540552-scaled.jpg?resize=1242%2C1536&amp;ssl=1 1242w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/20220101_1540552-scaled.jpg?resize=1656%2C2048&amp;ssl=1 1656w, https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/20220101_1540552-scaled.jpg?w=2000&amp;ssl=1 2000w\" sizes=\"auto, (max-width: 414px) 100vw, 414px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Didier Tronchet quitte l&#8217;Occident pour l&#8217;\u00eele aux Nattes, Oc\u00e9an Indien, avec son fils de 13 ans. Quitter la civilisation, retourner au vrai, vivre. Deux \u00e9v\u00e9nements inattendus. L&#8217;auteur pensait renforcer le lien avec son fils, le prot\u00e9ger, le cajoler, mais celui-ci s&#8217;adapte \u00e0 l&#8217;ile et \u00e0 sa nouvelle vie une aisance qui \u00e9tonne le p\u00e8re. Et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7934,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[103],"tags":[20,47,62],"class_list":["post-7933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graphic-2021","tag-adolescence","tag-humour","tag-quest"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2021\/12\/tom-winckels-I7oLRdM9YIw-unsplash-scaled.jpg?fit=2560%2C1702&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=7933"}],"version-history":[{"count":5,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7933\/revisions"}],"predecessor-version":[{"id":8100,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/7933\/revisions\/8100"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/7934"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=7933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=7933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=7933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}