{"id":8087,"date":"2021-12-04T12:07:00","date_gmt":"2021-12-04T11:07:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=8087"},"modified":"2022-01-01T12:07:39","modified_gmt":"2022-01-01T11:07:39","slug":"conte-du-yemenite-et-de-ses-six-esclaves-nuits-334-a-338","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/12\/04\/conte-du-yemenite-et-de-ses-six-esclaves-nuits-334-a-338\/","title":{"rendered":"Conte du Y\u00e9m\u00e9nite et de ses six esclaves &#8211; Nuits 334 \u00e0 338"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un Y\u00e9m\u00e9nite a six esclaves. Par pairs, elles vont devoir faire l&#8217;\u00e9loge et la critique l&#8217;une de l&#8217;autre : la blanche contre la noire, la grasse contre la mince et la jaune contre la brune. C&#8217;est joyeusement cruel, mais plut\u00f4t dr\u00f4le, car chacune se fait correctement remettre en place par l&#8217;autre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;On n&#8217;a jamais vu personne aller chez le boucher sinon que pour lui r\u00e9clamer une viande grasse, et les sages ont dit qu&#8217;il y avait trois plaisirs en ce monde: manger la chair, chevaucher la chair et fourrer la chair dans la chair. Quant \u00e0 toi, la mince, tes jambes sont comme des pattes d&#8217;oiseau ou des tisonniers, et toi la planche du crucifi\u00e9, ou de la viande avari\u00e9e. Rien en toi ne r\u00e9jouit l&#8217;\u0153il.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un Y\u00e9m\u00e9nite a six esclaves. Par pairs, elles vont devoir faire l&#8217;\u00e9loge et la critique l&#8217;une de l&#8217;autre : la blanche contre la noire, la grasse contre la mince et la jaune contre la brune. C&#8217;est joyeusement cruel, mais plut\u00f4t dr\u00f4le, car chacune se fait correctement remettre en place par l&#8217;autre. &#8220;On n&#8217;a jamais vu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8088,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[19,43,32],"class_list":["post-8087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-mille-et-une-nuits","tag-love","tag-racism","tag-women"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2022\/01\/md-mahdi-m43TF6wBrxw-unsplash-scaled.jpg?fit=1707%2C2560&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/8087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=8087"}],"version-history":[{"count":3,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/8087\/revisions"}],"predecessor-version":[{"id":8091,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/8087\/revisions\/8091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/8088"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=8087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=8087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=8087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}