{"id":8152,"date":"2021-12-13T21:17:00","date_gmt":"2021-12-13T20:17:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=8152"},"modified":"2022-01-03T14:20:47","modified_gmt":"2022-01-03T13:20:47","slug":"conte-du-mariage-dibrahim-b-al-mahdi-nuits-346-et-347","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2021\/12\/13\/conte-du-mariage-dibrahim-b-al-mahdi-nuits-346-et-347\/","title":{"rendered":"Conte du mariage d&#8217;Ibr\u00e2h\u00eem b. al-Mahd\u00ee &#8211; Nuits 346 et 347"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ibr\u00e2h\u00eem b. al-Mahd\u00ee fait une promenade lorsqu&#8217;il aper\u00e7oit une main et un poignet des plus jolis derri\u00e8re une jalousie. Il s&#8217;invite dans cette maison et y mange. On lui demande ce qu&#8217;il d\u00e9sire et il r\u00e9pond qu&#8217;il voudrait voir cette main et ce poignet. On lui montre toutes les femmes de la maison et il reconnait la main et le poignet de la fille du ma\u00eetre de maison. March\u00e9 conclu, il l&#8217;\u00e9pouse \u00e0 la minute et s&#8217;en va chez lui avec. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Cette femme me bouleversa, Commandeur des croyants ; son extr\u00eame beaut\u00e9 et la d\u00e9licatesse m\u00eame des vers qu&#8217;elle venait de chanter me mirent dans un tel \u00e9moi que j&#8217;en vins \u00e0 lui envier son talent\u00a0:<br>&#8211; Tu pouvais faire encore mieux, ma fille&#8221;, lui dis-je.<\/em><br><em>Alors, furieuse, elle jeta le luth et s&#8217;\u00e9cria :<\/em><br>&#8211; <em>Va-t-on longtemps encore inviter ici des gens qui n&#8217;y entendent rien ?&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ibr\u00e2h\u00eem b. al-Mahd\u00ee fait une promenade lorsqu&#8217;il aper\u00e7oit une main et un poignet des plus jolis derri\u00e8re une jalousie. Il s&#8217;invite dans cette maison et y mange. On lui demande ce qu&#8217;il d\u00e9sire et il r\u00e9pond qu&#8217;il voudrait voir cette main et ce poignet. On lui montre toutes les femmes de la maison et il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[118,19,113],"class_list":["post-8152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-mille-et-une-nuits","tag-beauty","tag-love","tag-music"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2022\/01\/mostafa-meraji-VqWW_e4rmng-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/8152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=8152"}],"version-history":[{"count":2,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/8152\/revisions"}],"predecessor-version":[{"id":8160,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/8152\/revisions\/8160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/8151"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=8152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=8152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=8152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}