{"id":9775,"date":"2022-06-05T10:33:00","date_gmt":"2022-06-05T08:33:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=9775"},"modified":"2024-03-13T10:26:57","modified_gmt":"2024-03-13T09:26:57","slug":"inglourious-basterds-quentin-tarantino-2009","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2022\/06\/05\/inglourious-basterds-quentin-tarantino-2009\/","title":{"rendered":"Inglourious Basterds &#8211; Quentin Tarantino (2009)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">France, Seconde Guerre mondiale. Deux histoires en parall\u00e8le pour une m\u00eame finalit\u00e9. D&#8217;un c\u00f4t\u00e9, Shosanna Dreyfus, dont la famille a \u00e9t\u00e9 assassin\u00e9e par les nazis et qui r\u00eave de vengeance. Cette vengeance lui sera servie sur un plateau lorsque le dernier film produit par Goebbels sera diffus\u00e9 dans son cin\u00e9ma avec tout le gratin nazi pr\u00e9sent, y compris le F\u00fchrer. D&#8217;un autre c\u00f4t\u00e9, Aldo Raine, parachut\u00e9 en Europe pour tuer du nazi, ce qu&#8217;il parvient assez bien \u00e0 faire avec ses huit acolytes, scalpant au passage toutes leurs victimes. Pour eux aussi, le rassemblement dans le cin\u00e9ma permettra de finaliser leur mission. Un Tarantino, donc plein de sang partout mais aussi tr\u00e8s violent, tr\u00e8s cruel. Peut-\u00eatre trop proche d&#8217;une r\u00e9alit\u00e9 qui a exist\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;- Vous aviez pas dit que vous aviez rendez-vous au fond d&#8217;une putain de cave.<br>&#8211; Je l&#8217;ignorais.<br>&#8211; Vous aviez dit que c&#8217;\u00e9tait dans une taverne.<br>&#8211; C&#8217;est une taverne.<br>&#8211; Ouais, mais dans une cave. Et se battre au fond d&#8217;une cave, ben \u00e7a pr\u00e9sente des difficult\u00e9s. Et la premi\u00e8re d&#8217;entre elles, c&#8217;est qu&#8217;on se bat au fond d&#8217;une cave.&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-colibri-color-4-color\">Version originale en anglais &#8211; Regard\u00e9 en fran\u00e7ais<\/mark><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>France, Seconde Guerre mondiale. Deux histoires en parall\u00e8le pour une m\u00eame finalit\u00e9. D&#8217;un c\u00f4t\u00e9, Shosanna Dreyfus, dont la famille a \u00e9t\u00e9 assassin\u00e9e par les nazis et qui r\u00eave de vengeance. Cette vengeance lui sera servie sur un plateau lorsque le dernier film produit par Goebbels sera diffus\u00e9 dans son cin\u00e9ma avec tout le gratin nazi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9776,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[152],"tags":[59,112,190],"class_list":["post-9775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-films-2022","tag-crime","tag-history","tag-violence"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2022\/06\/john-moeses-bauan-WG1HNF8PGHo-unsplash-scaled-e1654506632357.jpg?fit=1707%2C1664&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/9775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=9775"}],"version-history":[{"count":2,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/9775\/revisions"}],"predecessor-version":[{"id":15111,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/9775\/revisions\/15111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/9776"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=9775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=9775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=9775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}