{"id":9813,"date":"2022-02-10T16:49:00","date_gmt":"2022-02-10T15:49:00","guid":{"rendered":"https:\/\/redheadwithabrain.ch\/?p=9813"},"modified":"2022-08-08T20:44:16","modified_gmt":"2022-08-08T18:44:16","slug":"conte-de-hind-fille-dan-numan-nuits-405-et-406","status":"publish","type":"post","link":"https:\/\/redheadwithabrain.ch\/index.php\/2022\/02\/10\/conte-de-hind-fille-dan-numan-nuits-405-et-406\/","title":{"rendered":"Conte de Hind, fille d&#8217;an-Nu&#8217;m\u00e2n &#8211; Nuits 405 et 406"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Hind tombe amoureuse de &#8216;Ad\u00ee b. Zayd, amour r\u00e9ciproque. La servante de Hind, Marie, manigance tout et leur permet de se marier avec l&#8217;accord de an-Nu&#8217;m\u00e2n, le p\u00e8re de Hind. Trois ans plus tard, les deux hommes se f\u00e2chent, an-Nu&#8217;m\u00e2n fait tuer &#8216;Ad\u00ee et Hind se retire dans un monast\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>&#8220;Le matin venu, il vit venir Marie, et lui qui jusque-l\u00e0 n&#8217;avait pas eu la moindre attention pour elle l&#8217;accueillit alors avec grande joie, lui demandant ce qu&#8217;elle voulait. &#8220;J&#8217;ai besoin de toi, dit-elle. Dis-moi donc ce que c&#8217;est. Par Dieu, je ne te laisserai rien me demander que je ne t&#8217;accorde.&#8221; Elle lui avoua qu&#8217;elle l&#8217;aimait et que son d\u00e9sir \u00e9tait de se retrouver seule avec lui. Il accepta \u00e0 la condition qu&#8217;elle mit tout en \u0153uvre pour les r\u00e9unir, Hind et lui, et l&#8217;emmena \u00e0 la boutique d&#8217;un marchand de vin, pr\u00e8s d&#8217;une porte d&#8217;al Hira, o\u00f9 il la poss\u00e9da.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hind tombe amoureuse de &#8216;Ad\u00ee b. Zayd, amour r\u00e9ciproque. La servante de Hind, Marie, manigance tout et leur permet de se marier avec l&#8217;accord de an-Nu&#8217;m\u00e2n, le p\u00e8re de Hind. Trois ans plus tard, les deux hommes se f\u00e2chent, an-Nu&#8217;m\u00e2n fait tuer &#8216;Ad\u00ee et Hind se retire dans un monast\u00e8re. &#8220;Le matin venu, il vit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9814,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[11],"tags":[],"class_list":["post-9813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-mille-et-une-nuits"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/redheadwithabrain.ch\/wp-content\/uploads\/2022\/06\/adli-wahid-Dc-iljQS6ig-unsplash-scaled.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/9813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/comments?post=9813"}],"version-history":[{"count":2,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/9813\/revisions"}],"predecessor-version":[{"id":10353,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/posts\/9813\/revisions\/10353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media\/9814"}],"wp:attachment":[{"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/media?parent=9813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/categories?post=9813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redheadwithabrain.ch\/index.php\/wp-json\/wp\/v2\/tags?post=9813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}